{"id":97197,"date":"2025-10-27T10:48:54","date_gmt":"2025-10-27T10:48:54","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/97197"},"modified":"2025-10-27T10:48:54","modified_gmt":"2025-10-27T10:48:54","slug":"%da%a9%d8%b1%d8%a7%d8%a6%d9%85-%d8%b3%db%8c%d8%b1%db%8c%d8%b2-%d8%af%db%8c%da%a9%da%be-%da%a9%d8%b1-%d9%85%d8%b9%d8%b4%d9%88%d9%82%db%81-%d9%86%db%92-%da%a9%d8%b1%d8%af%db%8c%d8%a7-%d8%b9%d8%a7%d8%b4","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/97197","title":{"rendered":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645"},"content":{"rendered":"<p><\/p>\n<div>\n<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u067e\u0627\u0631\u0679\u0645\u0646\u0679 \u0645\u06cc\u06ba \u067e\u06cc\u0634 \u0622\u0626\u06d2 \u0622\u062a\u0634\u0632\u062f\u06af\u06cc \u06a9\u06d2 \u0648\u0627\u0642\u0639\u06d2 \u0646\u06d2 \u0633\u0646\u0633\u0646\u06cc \u067e\u06be\u06cc\u0644\u0627 \u062f\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0633\u06cc\u0648\u0644 \u0633\u0631\u0648\u0633\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631 \u06a9\u06cc \u062c\u06be\u0644\u0633\u06cc \u06c1\u0648\u0626\u06cc \u0646\u0639\u0634 \u0645\u0644\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u062d\u0627\u062f\u062b\u06c1 \u0633\u0645\u062c\u06be\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u067e\u0648\u0644\u06cc\u0633<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0645\u06cc\u06ba \u0686\u0648\u0646\u06a9\u0627 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0646\u06a9\u0634\u0627\u0641\u0627\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u062d\u0627\u062f\u062b\u06c1 \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u06cc \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0644\u0691\u06a9\u06cc \u0646\u06d2 \u06c1\u06cc \u0628\u06d2 \u062f\u0631\u062f\u06cc \u0633\u06d2 \u0642\u062a\u0644 \u06a9\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u0644\u0632\u0645\u06c1 \u06a9\u0648 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u0631\u0644\u06cc\u0627 \u06c1\u06d2\u06d4\u062a\u0641\u0635\u06cc\u0644\u0627\u062a \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06cc\u06c1 \u0648\u0627\u0642\u0639\u06c1 6 \u0627\u06a9\u062a\u0648\u0628\u0631 \u06a9\u0648<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u0634\u0645\u0627\u0644\u06cc \u062f\u06c1\u0644\u06cc \u06a9\u06d2 \u062a\u0650\u0645\u0627\u0631 \u067e\u0648\u0631 \u0639\u0644\u0627\u0642\u06d2 \u0645\u06cc\u06ba \u067e\u06cc\u0634 \u0622\u06cc\u0627\u06d4 \u0645\u0642\u0627\u0645\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648 \u0627\u06cc\u06a9 \u0639\u0645\u0627\u0631\u062a \u0645\u06cc\u06ba \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u06cc \u062c\u0633 \u067e\u0631 \u0679\u06cc\u0645 \u0645\u0648\u0642\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686\u06cc \u062a\u0648 \u0686\u0648\u062a\u06be\u06cc \u0645\u0646\u0632\u0644 \u06a9\u06d2 \u0641\u0644\u06cc\u0679 \u0645\u06cc\u06ba \u062c\u0644\u06cc \u06c1\u0648\u0626\u06cc \u0646\u0639\u0634 \u0628\u0631\u0622\u0645\u062f \u06c1\u0648\u0626\u06cc\u06d4 \u0645\u062a\u0648\u0641\u06cc \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a 32 \u0633\u0627\u0644\u06c1 \u0631\u0627\u0645 \u06a9\u06cc\u0634 \u0645\u06cc\u0646\u0627<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u06c1\u0648\u0626\u06cc\u06d4 \u0627\u0631\u06a9\u0627\u0646 \u062e\u0627\u0646\u062f\u0627\u0646 \u0646\u06d2 \u0634\u0628\u06c1 \u0638\u0627\u06c1\u0631 \u06a9\u06cc\u0627 \u06a9\u06c1 \u06cc\u06c1 \u062d\u0627\u062f\u062b\u06c1 \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0642\u062a\u0644 \u06c1\u06d2\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u0642\u062f\u0645\u06c1 \u062f\u0631\u062c \u06a9\u0631 \u06a9\u06d2 \u062a\u0641\u062a\u06cc\u0634 \u0634\u0631\u0648\u0639 \u06a9\u06cc\u06d4\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0633\u06cc \u0633\u06cc \u0679\u06cc \u0648\u06cc \u0641\u0648\u0679\u06cc\u062c \u0645\u06cc\u06ba \u0627\u0646\u06a9\u0634\u0627\u0641 \u06c1\u0648\u0627 \u06a9\u06c1 \u0648\u0627\u0642\u0639\u06d2 \u0633\u06d2 \u06a9\u0686\u06be \u062f\u06cc\u0631 \u0642\u0628\u0644 \u062f\u0648 \u0627\u0641\u0631\u0627\u062f \u0645\u0627\u0633\u06a9 \u067e\u06c1\u0646\u06d2 \u0639\u0645\u0627\u0631\u062a<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u0645\u06cc\u06ba \u062f\u0627\u062e\u0644 \u06c1\u0648\u0626\u06d2 \u062c\u0646 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u06cc\u06a9 \u0644\u0691\u06a9\u06cc \u0628\u06be\u06cc \u0648\u06c1\u0627\u06ba \u0633\u06d2 \u0628\u0627\u06c1\u0631 \u0622\u062a\u06cc \u062f\u06cc\u06a9\u06be\u06cc \u06af\u0626\u06cc\u06d4 \u0627\u0646 \u06a9\u06d2 \u062c\u0627\u0646\u06d2 \u06a9\u06d2 \u06a9\u0686\u06be \u06c1\u06cc \u062f\u06cc\u0631 \u0628\u0639\u062f \u062f\u06be\u0645\u0627\u06a9\u06c1 \u06c1\u0648\u0627\u06d4 \u0641\u0648\u0679\u06cc\u062c \u06a9\u06cc \u0645\u062f\u062f \u0633\u06d2 \u0627\u0633 \u0644\u0691\u06a9\u06cc \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a 21 \u0633\u0627\u0644\u06c1 \u0627\u0645\u0631\u062a\u0627 \u0686\u0648\u06c1\u0627\u0646 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u06c1\u0648\u0626\u06cc \u062c\u0648 \u0641\u0648\u0631\u06cc\u0646\u0633\u06a9 \u0633\u0627\u0626\u0646\u0633\u0633 \u06a9\u06cc \u0637\u0627\u0644\u0628\u06c1 \u06c1\u06d2\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0633\u06d2 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u062a\u0648 \u0645\u0639\u0627\u0645\u0644\u06d2 \u06a9\u06cc \u062d\u0642\u06cc\u0642\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u06af\u0626\u06cc\u06d4\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u0645\u0631\u062a\u0627 \u0627\u0648\u0631 \u0631\u0627\u0645 \u06a9\u06cc\u0634 \u06a9\u0686\u06be \u0639\u0631\u0635\u06d2 \u0633\u06d2 \u0627\u06cc\u06a9 \u0633\u0627\u062a\u06be \u0631\u06c1 \u0631\u06c1\u06d2 \u062a\u06be\u06d2\u06d4 \u0627\u0633 \u062f\u0648\u0631\u0627\u0646 \u0631\u0627\u0645 \u06a9\u06cc\u0634 \u0646\u06d2 \u0627\u0645\u0631\u062a\u0627 \u06a9\u06cc \u0646\u062c\u06cc \u0648\u06cc\u0688\u06cc\u0648\u0632 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u06a9\u0631 \u06a9\u06d2 \u06c1\u0627\u0631\u0688 \u0688\u0633\u06a9 \u0645\u06cc\u06ba \u0645\u062d\u0641\u0648\u0638 \u06a9\u0631 \u0631\u06a9\u06be\u06cc \u062a\u06be\u06cc\u06ba\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u062c\u0628 \u0627\u0645\u0631\u062a\u0627 \u0646\u06d2 \u0627\u0646 \u0648\u06cc\u0688\u06cc\u0648\u0632 \u06a9\u0648 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u06cc\u0627 \u0627\u0648\u0631 \u0631\u0627\u0645 \u06a9\u06cc\u0634 \u0646\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u06a9\u06cc\u0627 \u062a\u0648 \u0627\u0633 \u0646\u06d2 \u063a\u0635\u06d2 \u0645\u06cc\u06ba \u0622 \u06a9\u0631 \u0627\u0633\u06d2 \u0642\u062a\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u0645\u0646\u0635\u0648\u0628\u06c1 \u0628\u0646\u0627\u06cc\u0627\u06d4 \u0627\u0633 \u0633\u0627\u0632\u0634 \u0645\u06cc\u06ba \u0627\u0633 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0633\u0627\u0628\u0642 \u0639\u0627\u0634\u0642 \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u062a \u06a9\u06cc \u0645\u062f\u062f \u0644\u06cc\u06d4 5 \u0627\u06a9\u062a\u0648\u0628\u0631 \u06a9\u06cc \u0631\u0627\u062a \u0627\u0645\u0631\u062a\u0627 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u0633\u0627\u062a\u06be\u06cc\u0648\u06ba \u0646\u06d2 \u0631\u0627\u0645 \u06a9\u06cc\u0634 \u06a9\u0627 \u06af\u0644\u0627 \u06af\u06be\u0648\u0646\u0679 \u06a9\u0631 \u0642\u062a\u0644 \u06a9\u06cc\u0627\u06d4 \u0628\u0639\u062f \u0627\u0632\u0627\u06ba \u0646\u0639\u0634 \u067e\u0631 \u06af\u06be\u06cc\u060c \u062a\u06cc\u0644 \u0627\u0648\u0631 \u0634\u0631\u0627\u0628 \u0688\u0627\u0644 \u06a9\u0631 \u06a9\u0686\u0646 \u0633\u06d2 \u06af\u06cc\u0633 \u0633\u0644\u0646\u0688\u0631 \u0644\u0627 \u06a9\u0631 \u0627\u0633 \u06a9\u0627 \u067e\u0627\u0626\u067e \u06a9\u0627\u0679\u0627 \u0627\u0648\u0631 \u0646\u0639\u0634 \u06a9\u0648 \u0622\u06af \u0644\u06af\u0627 \u062f\u06cc\u06d4 \u0641\u0644\u06cc\u0679 \u06a9\u0627 \u0645\u06cc\u0646 \u062f\u0631\u0648\u0627\u0632\u06c1 \u0628\u0646\u062f \u06a9\u0631 \u06a9\u06d2 \u0648\u06c1 \u0641\u0631\u0627\u0631 \u06c1\u0648\u06af\u0626\u06d2\u06d4 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0645\u06cc\u06ba \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648 \u0645\u0639\u0644\u0648\u0645 \u06c1\u0648\u0627 \u06a9\u06c1 \u0644\u0691\u06a9\u06cc \u0646\u06d2 \u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0642\u062a\u0644 \u06a9\u0627 \u0645\u0646\u0635\u0648\u0628\u06c1 \u0628\u0646\u0627\u06cc\u0627 \u062a\u06be\u0627\u06d4<\/p>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u067e\u0627\u0631\u0679\u0645\u0646\u0679 \u0645\u06cc\u06ba \u067e\u06cc\u0634 \u0622\u0626\u06d2 \u0622\u062a\u0634\u0632\u062f\u06af\u06cc \u06a9\u06d2 \u0648\u0627\u0642\u0639\u06d2 \u0646\u06d2 \u0633\u0646\u0633\u0646\u06cc \u067e\u06be\u06cc\u0644\u0627 \u062f\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0633\u06cc\u0648\u0644 \u0633\u0631\u0648\u0633\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631 \u06a9\u06cc \u062c\u06be\u0644\u0633\u06cc \u06c1\u0648\u0626\u06cc \u0646\u0639\u0634 \u0645\u0644\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u062d\u0627\u062f\u062b\u06c1 \u0633\u0645\u062c\u06be\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u067e\u0648\u0644\u06cc\u0633 \u00a0 \u00a0 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0645\u06cc\u06ba \u0686\u0648\u0646\u06a9\u0627 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0646\u06a9\u0634\u0627\u0641\u0627\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u062d\u0627\u062f\u062b\u06c1&#8230;<\/p>\n","protected":false},"author":1,"featured_media":97198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-97197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/97197\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -\" \/>\n<meta property=\"og:description\" content=\"\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u067e\u0627\u0631\u0679\u0645\u0646\u0679 \u0645\u06cc\u06ba \u067e\u06cc\u0634 \u0622\u0626\u06d2 \u0622\u062a\u0634\u0632\u062f\u06af\u06cc \u06a9\u06d2 \u0648\u0627\u0642\u0639\u06d2 \u0646\u06d2 \u0633\u0646\u0633\u0646\u06cc \u067e\u06be\u06cc\u0644\u0627 \u062f\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0633\u06cc\u0648\u0644 \u0633\u0631\u0648\u0633\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631 \u06a9\u06cc \u062c\u06be\u0644\u0633\u06cc \u06c1\u0648\u0626\u06cc \u0646\u0639\u0634 \u0645\u0644\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u062d\u0627\u062f\u062b\u06c1 \u0633\u0645\u062c\u06be\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u067e\u0648\u0644\u06cc\u0633 \u00a0 \u00a0 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0645\u06cc\u06ba \u0686\u0648\u0646\u06a9\u0627 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0646\u06a9\u0634\u0627\u0641\u0627\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u062d\u0627\u062f\u062b\u06c1...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/97197\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T10:48:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1313\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645\",\"datePublished\":\"2025-10-27T10:48:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg\",\"articleSection\":[\"\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/97197#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/97197\",\"name\":\"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg\",\"datePublished\":\"2025-10-27T10:48:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/97197\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg\",\"width\":1071,\"height\":855},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/97197#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/97197","og_locale":"en_US","og_type":"article","og_title":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -","og_description":"\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u067e\u0627\u0631\u0679\u0645\u0646\u0679 \u0645\u06cc\u06ba \u067e\u06cc\u0634 \u0622\u0626\u06d2 \u0622\u062a\u0634\u0632\u062f\u06af\u06cc \u06a9\u06d2 \u0648\u0627\u0642\u0639\u06d2 \u0646\u06d2 \u0633\u0646\u0633\u0646\u06cc \u067e\u06be\u06cc\u0644\u0627 \u062f\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0633\u06cc\u0648\u0644 \u0633\u0631\u0648\u0633\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631 \u06a9\u06cc \u062c\u06be\u0644\u0633\u06cc \u06c1\u0648\u0626\u06cc \u0646\u0639\u0634 \u0645\u0644\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u062d\u0627\u062f\u062b\u06c1 \u0633\u0645\u062c\u06be\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u067e\u0648\u0644\u06cc\u0633 \u00a0 \u00a0 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0645\u06cc\u06ba \u0686\u0648\u0646\u06a9\u0627 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0646\u06a9\u0634\u0627\u0641\u0627\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u062d\u0627\u062f\u062b\u06c1...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/97197","article_published_time":"2025-10-27T10:48:54+00:00","og_image":[{"width":1313,"height":560,"url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645","datePublished":"2025-10-27T10:48:54+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg","articleSection":["\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/97197#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/97197","url":"https:\/\/safirnews.in\/urdu\/archives\/97197","name":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg","datePublished":"2025-10-27T10:48:54+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/97197"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/10\/20251027_153418-1.jpg","width":1071,"height":855},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/97197#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u06a9\u0631\u0627\u0626\u0645 \u0633\u06cc\u0631\u06cc\u0632 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0645\u0639\u0634\u0648\u0642\u06c1 \u0646\u06d2 \u06a9\u0631\u062f\u06cc\u0627 \u0639\u0627\u0634\u0642 \u06a9\u0627 \u0642\u062a\u0644\u06d4 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0648\u06cc\u0688\u06cc\u0648\u0633 \u0688\u06cc\u0644\u06cc\u0679 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0646\u06a9\u0627\u0631 \u067e\u0631 \u0627\u0646\u062a\u0642\u0627\u0645"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/97197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=97197"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/97197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/97198"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=97197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=97197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=97197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}