{"id":73295,"date":"2025-05-31T13:11:40","date_gmt":"2025-05-31T13:11:40","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/73295"},"modified":"2025-05-31T13:11:40","modified_gmt":"2025-05-31T13:11:40","slug":"%da%86%d8%a7%d8%af%d8%b1%da%af%da%be%d8%a7%d9%b9-%d8%b3%db%92-%d8%af%d9%84%d8%b3%da%a9%da%be-%d9%86%da%af%d8%b1-%da%a9%db%8c-%d8%b3%d9%85%d8%aa-%d8%ac%d8%a7%d9%86%db%92-%d9%88%d8%a7%d9%84%db%92-%d9%85","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/73295","title":{"rendered":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633"},"content":{"rendered":"<p><\/p>\n<div id=\"the-post\">\n<div class=\"featured-area\">\n<div class=\"featured-area-inner\">\n<figure class=\"single-featured-image\"><img width=\"780\" height=\"470\" src=\"https:\/\/urduleaks.com\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1-780x470.jpg\" class=\"attachment-jannah-image-post size-jannah-image-post wp-post-image\" alt=\"\" is_main_img=\"1\" decoding=\"async\" fetchpriority=\"high\"\/><\/figure>\n<\/div>\n<\/div>\n<div class=\"entry-content entry clearfix\">\n<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f: \u0645\u0644\u06a9 \u067e\u06cc\u0679 \u06a9\u06d2 \u0627\u06a9\u0628\u0631 \u067e\u0644\u0627\u0632\u06c1 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u062c\u0645\u0639\u06c1 \u06a9\u06cc \u0635\u0628\u062d \u0633\u06d2 \u0688\u0631\u06cc\u0646\u062c \u06a9\u0627 \u06af\u0646\u062f\u06c1 \u067e\u0627\u0646\u06cc \u0633\u0691\u06a9\u0648\u06ba \u067e\u0631 \u0627\u064f\u0628\u0644 \u06a9\u0631 \u0628\u06c1\u0646\u06d2 \u0644\u06af\u0627 \u062c\u0633 \u06a9\u06d2 \u0646\u062a\u06cc\u062c\u06d2 \u0645\u06cc\u06ba \u0679\u0631\u06cc\u0641\u06a9 \u0634\u062f\u06cc\u062f \u0637\u0648\u0631 \u067e\u0631 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u0626\u06cc \u0627\u0648\u0631 \u06af\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u0622\u0645\u062f\u0648\u0631\u0641\u062a \u0645\u06cc\u06ba \u062e\u0644\u0644 \u067e\u06cc\u062f \u0627 \u06c1\u0648\u0631\u06c1\u0627<\/p>\n<p>\u00a0<\/p>\n<p>\u06c1\u06d2\u060c \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u06a9\u0627 \u0646\u0648\u0679\u0633 \u0644\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0633\u0631\u06a9\u0627\u0631\u06cc \u0639\u0645\u0644\u06c1 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631 \u0645\u0648\u0642\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06a9\u0631 \u0645\u0631\u0645\u062a \u06a9\u0627 \u06a9\u0627\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u0627\u06d4 \u062d\u06a9\u0627\u0645 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06cc\u06c1 \u0645\u0631\u0645\u062a\u06cc \u06a9\u0627\u0645 \u0627\u062a\u0648\u0627\u0631 \u06a9\u0648 \u0628\u06be\u06cc \u062c\u0627\u0631\u06cc \u0631\u06c1\u06cc\u06ba \u06af\u06d2\u06d4\u0679\u0631\u06cc\u0641\u06a9 \u0688\u06cc \u0633\u06cc \u067e\u06cc \u0648\u06cc\u0646\u06a9\u0679\u06cc\u0634\u0648\u0631\u0644\u0648<\/p>\n<p>\u00a0<\/p>\n<p>\u0646\u06d2 \u0639\u0648\u0627\u0645 \u0633\u06d2 \u0627\u067e\u06cc\u0644 \u06a9\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0637\u0631\u0641 \u0633\u0641\u0631 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u0633\u0627\u0641\u0631 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u0648\u06ba \u06a9\u0627 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u0645\u0646\u0632\u0644 \u062a\u06a9 \u0628\u0622\u0633\u0627\u0646\u06cc \u067e\u06c1\u0646\u0686 \u0633\u06a9\u06cc\u06ba\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06af\u0627\u0691\u06cc \u0633\u0648\u0627\u0631\u0648\u06ba \u0633\u06d2 \u0679\u0631\u06cc\u0641\u06a9 \u067e\u0648\u0644\u06cc\u0633<\/p>\n<p>\u00a0<\/p>\n<p>\u0633\u06d2 \u062a\u0639\u0627\u0648\u0646 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u0628\u06be\u06cc \u06a9\u06cc \u06c1\u06d2\u06d4<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f: \u0645\u0644\u06a9 \u067e\u06cc\u0679 \u06a9\u06d2 \u0627\u06a9\u0628\u0631 \u067e\u0644\u0627\u0632\u06c1 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u062c\u0645\u0639\u06c1 \u06a9\u06cc \u0635\u0628\u062d \u0633\u06d2 \u0688\u0631\u06cc\u0646\u062c \u06a9\u0627 \u06af\u0646\u062f\u06c1 \u067e\u0627\u0646\u06cc \u0633\u0691\u06a9\u0648\u06ba \u067e\u0631 \u0627\u064f\u0628\u0644 \u06a9\u0631 \u0628\u06c1\u0646\u06d2 \u0644\u06af\u0627 \u062c\u0633 \u06a9\u06d2 \u0646\u062a\u06cc\u062c\u06d2 \u0645\u06cc\u06ba \u0679\u0631\u06cc\u0641\u06a9 \u0634\u062f\u06cc\u062f \u0637\u0648\u0631 \u067e\u0631 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u0626\u06cc \u0627\u0648\u0631 \u06af\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u0622\u0645\u062f\u0648\u0631\u0641\u062a \u0645\u06cc\u06ba \u062e\u0644\u0644 \u067e\u06cc\u062f \u0627 \u06c1\u0648\u0631\u06c1\u0627 \u00a0 \u06c1\u06d2\u060c \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u06a9\u0627 \u0646\u0648\u0679\u0633 \u0644\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0633\u0631\u06a9\u0627\u0631\u06cc \u0639\u0645\u0644\u06c1 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631&#8230;<\/p>\n","protected":false},"author":1,"featured_media":73296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-73295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hyderabad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/73295\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -\" \/>\n<meta property=\"og:description\" content=\"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f: \u0645\u0644\u06a9 \u067e\u06cc\u0679 \u06a9\u06d2 \u0627\u06a9\u0628\u0631 \u067e\u0644\u0627\u0632\u06c1 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u062c\u0645\u0639\u06c1 \u06a9\u06cc \u0635\u0628\u062d \u0633\u06d2 \u0688\u0631\u06cc\u0646\u062c \u06a9\u0627 \u06af\u0646\u062f\u06c1 \u067e\u0627\u0646\u06cc \u0633\u0691\u06a9\u0648\u06ba \u067e\u0631 \u0627\u064f\u0628\u0644 \u06a9\u0631 \u0628\u06c1\u0646\u06d2 \u0644\u06af\u0627 \u062c\u0633 \u06a9\u06d2 \u0646\u062a\u06cc\u062c\u06d2 \u0645\u06cc\u06ba \u0679\u0631\u06cc\u0641\u06a9 \u0634\u062f\u06cc\u062f \u0637\u0648\u0631 \u067e\u0631 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u0626\u06cc \u0627\u0648\u0631 \u06af\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u0622\u0645\u062f\u0648\u0631\u0641\u062a \u0645\u06cc\u06ba \u062e\u0644\u0644 \u067e\u06cc\u062f \u0627 \u06c1\u0648\u0631\u06c1\u0627 \u00a0 \u06c1\u06d2\u060c \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u06a9\u0627 \u0646\u0648\u0679\u0633 \u0644\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0633\u0631\u06a9\u0627\u0631\u06cc \u0639\u0645\u0644\u06c1 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/73295\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-31T13:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/urduleaks.com\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1-780x470.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633\",\"datePublished\":\"2025-05-31T13:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg\",\"articleSection\":[\"\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/73295#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/73295\",\"name\":\"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg\",\"datePublished\":\"2025-05-31T13:11:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/73295\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg\",\"width\":1453,\"height\":964},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/73295#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/73295","og_locale":"en_US","og_type":"article","og_title":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -","og_description":"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f: \u0645\u0644\u06a9 \u067e\u06cc\u0679 \u06a9\u06d2 \u0627\u06a9\u0628\u0631 \u067e\u0644\u0627\u0632\u06c1 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u062c\u0645\u0639\u06c1 \u06a9\u06cc \u0635\u0628\u062d \u0633\u06d2 \u0688\u0631\u06cc\u0646\u062c \u06a9\u0627 \u06af\u0646\u062f\u06c1 \u067e\u0627\u0646\u06cc \u0633\u0691\u06a9\u0648\u06ba \u067e\u0631 \u0627\u064f\u0628\u0644 \u06a9\u0631 \u0628\u06c1\u0646\u06d2 \u0644\u06af\u0627 \u062c\u0633 \u06a9\u06d2 \u0646\u062a\u06cc\u062c\u06d2 \u0645\u06cc\u06ba \u0679\u0631\u06cc\u0641\u06a9 \u0634\u062f\u06cc\u062f \u0637\u0648\u0631 \u067e\u0631 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u0626\u06cc \u0627\u0648\u0631 \u06af\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u0622\u0645\u062f\u0648\u0631\u0641\u062a \u0645\u06cc\u06ba \u062e\u0644\u0644 \u067e\u06cc\u062f \u0627 \u06c1\u0648\u0631\u06c1\u0627 \u00a0 \u06c1\u06d2\u060c \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u06a9\u0627 \u0646\u0648\u0679\u0633 \u0644\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0633\u0631\u06a9\u0627\u0631\u06cc \u0639\u0645\u0644\u06c1 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/73295","article_published_time":"2025-05-31T13:11:40+00:00","og_image":[{"url":"https:\/\/urduleaks.com\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1-780x470.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633","datePublished":"2025-05-31T13:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg","articleSection":["\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/73295#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/73295","url":"https:\/\/safirnews.in\/urdu\/archives\/73295","name":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg","datePublished":"2025-05-31T13:11:40+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/73295"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/05\/20250531_171721-1-1.jpg","width":1453,"height":964},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/73295#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u0686\u0627\u062f\u0631\u06af\u06be\u0627\u0679 \u0633\u06d2 \u062f\u0644\u0633\u06a9\u06be \u0646\u06af\u0631 \u06a9\u06cc \u0633\u0645\u062a \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u062a\u0628\u0627\u062f\u0644 \u0631\u0627\u0633\u062a\u06c1 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba:\u067e\u0648\u0644\u06cc\u0633"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/73295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=73295"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/73295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/73296"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=73295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=73295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=73295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}