{"id":60901,"date":"2025-03-25T21:07:31","date_gmt":"2025-03-25T21:07:31","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/60901"},"modified":"2025-03-25T21:07:31","modified_gmt":"2025-03-25T21:07:31","slug":"%d9%81%d9%84%d8%b3%d8%b7%db%8c%d9%86-%da%a9%db%8c-%d8%ad%d9%85%d8%a7%db%8c%d8%aa-%d8%ad%d8%b6%d8%b1%d8%aa-%d8%b9%db%8c%d8%b3%db%8c-%d8%b9-%d8%a7%d9%88%d8%b1-%d8%a7%d9%85%d8%a7%d9%85-%d8%ad%d8%b3","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/60901","title":{"rendered":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/media.mehrnews.com\/d\/2025\/03\/25\/4\/5436787.jpg\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><strong>\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0<\/strong>\u06a9\u06cc \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u063a\u0632\u06c1 \u067e\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u0641\u0648\u0631\u0633\u0632 \u06a9\u06d2 \u062f\u0648\u0628\u0627\u0631\u06c1 \u062d\u0645\u0644\u06d2 \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0645\u062e\u062a\u0644\u0641 \u0645\u0642\u0627\u0645\u0627\u062a \u067e\u0631 \u0645\u0638\u0627\u06c1\u0631\u06d2 \u06c1\u0648\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0631\u0646\u06af\u060c \u0646\u0633\u0644 \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628 \u06a9\u06cc \u062a\u0641\u0631\u06cc\u0642 \u0633\u06d2 \u0628\u0627\u0644\u0627\u062a\u0631 \u06c1\u0648\u06a9\u0631 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u062d\u0642 \u0645\u06cc\u06ba \u0627\u0648\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4<\/p>\n<p>\u0627\u0633\u06cc \u0645\u0646\u0627\u0633\u0628\u062a \u0633\u06d2 \u06a9\u06cc\u0646\u06cc\u0688\u0627 \u06a9\u06d2 \u0634\u06c1\u0631 \u0679\u0648\u0631\u0646\u0679\u0648 \u0645\u06cc\u06ba \u0634\u06c1\u0631\u06cc\u0648\u06ba \u0646\u06d2 \u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u067e\u06cc\u062f\u0644 \u0645\u0627\u0631\u0686 \u06a9\u06cc\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u06c1\u0632\u0627\u0631 \u0633\u06d2 \u0632\u0627\u0626\u062f \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0634\u0631\u06a9\u062a \u06a9\u06cc\u06d4<\/p>\n<p>\u0645\u0627\u0631\u0686 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc \u0645\u0632\u0627\u062d\u0645\u062a \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc\u06ba \u06a9\u06cc\u0646\u06cc\u0688\u0627 \u06a9\u06d2 \u0648\u06a9\u06cc\u0644 \u0627\u0648\u0631 \u0635\u062d\u0627\u0641\u06cc \u062f\u06cc\u0645\u06cc\u062a\u0631\u06cc \u0644\u0627\u0633\u06a9\u0627\u0631\u06cc\u0633 \u06a9\u06d2 \u062e\u0637\u0627\u0628 \u0646\u06d2 \u0634\u0631\u06a9\u0627\u0621 \u06a9\u0627 \u062f\u0644 \u062c\u06cc\u062a\u0627\u06d4<\/p>\n<p>\u0644\u0627\u0633\u06a9\u0627\u0631\u06cc\u0633 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u062e\u0637\u0627\u0628 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u0622\u062c \u0641\u0644\u0633\u0637\u06cc\u0646\u060c \u06a9\u0631\u0628\u0644\u0627 \u06c1\u06d2\u061b \u063a\u0632\u06c1 \u06a9\u0631\u0628\u0644\u0627 \u06c1\u06d2\u061b \u0628\u06cc\u062a \u0627\u0644\u0645\u0642\u062f\u0633\u060c \u06a9\u0631\u0628\u0644\u0627 \u06c1\u06d2\u06d4 \u062c\u06c1\u0627\u06ba \u0628\u06be\u06cc \u06c1\u0645 \u0638\u0644\u0645 \u0627\u0648\u0631 \u0642\u0628\u0636\u06d2 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062d\u0642\u06cc\u0642\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06be\u0691\u06d2 \u06c1\u0648\u06ba\u060c \u0648\u06c1 \u06a9\u0631\u0628\u0644\u0627 \u06c1\u06d2\u06d4 \u06c1\u0645 \u0622\u062c \u062d\u0642\u06cc\u0642\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06be\u0691\u06d2 \u06c1\u06cc\u06ba\u06d4<\/p>\n<p>\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc\u0670 (\u0639) \u06a9\u0648 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc\u0648\u06ba \u06a9\u06d2 \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0633\u0628 \u0633\u06d2 \u067e\u0631\u0627\u0646\u06d2 \u0645\u062c\u0627\u06c1\u062f\u06cc\u0646 \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06cc\u06a9 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06c1\u0645 \u0646\u06d2 \u0627\u0646 \u0633\u06d2 \u0633\u06cc\u06a9\u06be\u0627 \u06a9\u06c1 \u06c1\u0645\u06cc\u0634\u06c1 \u062d\u0642\u06cc\u0642\u062a \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06d2 \u0631\u06c1\u0646\u0627 \u0686\u0627\u06c1\u06cc\u06d2\u06d4<\/p>\n<p>\u0644\u0627\u0633\u06a9\u0627\u0631\u06cc\u0633 \u06a9\u0627 \u0645\u0642\u0635\u062f \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc\u0670 (\u0639) \u06a9\u06cc \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc\u0648\u06ba \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u06a9\u06cc \u06cc\u0627\u062f \u062f\u06c1\u0627\u0646\u06cc \u06a9\u0631\u0627\u0646\u0627 \u062a\u06be\u0627\u060c \u062c\u0648 \u06c1\u0645\u06cc\u0634\u06c1 \u0645\u0638\u0644\u0648\u0645\u0648\u06ba \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc\u06ba \u0627\u0648\u0631 \u0638\u0627\u0644\u0645\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u06a9\u06be\u0691\u06d2 \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u062f\u0639\u0648\u062a \u062f\u06cc\u062a\u06d2 \u062a\u06be\u06d2\u06d4<\/p>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u06a9\u06cc \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u063a\u0632\u06c1 \u067e\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u0641\u0648\u0631\u0633\u0632 \u06a9\u06d2 \u062f\u0648\u0628\u0627\u0631\u06c1 \u062d\u0645\u0644\u06d2 \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0645\u062e\u062a\u0644\u0641 \u0645\u0642\u0627\u0645\u0627\u062a \u067e\u0631 \u0645\u0638\u0627\u06c1\u0631\u06d2 \u06c1\u0648\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0631\u0646\u06af\u060c \u0646\u0633\u0644 \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628 \u06a9\u06cc \u062a\u0641\u0631\u06cc\u0642 \u0633\u06d2 \u0628\u0627\u0644\u0627\u062a\u0631 \u06c1\u0648\u06a9\u0631 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u062d\u0642 \u0645\u06cc\u06ba \u0627\u0648\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u0633\u06cc \u0645\u0646\u0627\u0633\u0628\u062a \u0633\u06d2 \u06a9\u06cc\u0646\u06cc\u0688\u0627 \u06a9\u06d2&#8230;<\/p>\n","protected":false},"author":1,"featured_media":60902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-60901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/60901\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -\" \/>\n<meta property=\"og:description\" content=\"\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u06a9\u06cc \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u063a\u0632\u06c1 \u067e\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u0641\u0648\u0631\u0633\u0632 \u06a9\u06d2 \u062f\u0648\u0628\u0627\u0631\u06c1 \u062d\u0645\u0644\u06d2 \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0645\u062e\u062a\u0644\u0641 \u0645\u0642\u0627\u0645\u0627\u062a \u067e\u0631 \u0645\u0638\u0627\u06c1\u0631\u06d2 \u06c1\u0648\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0631\u0646\u06af\u060c \u0646\u0633\u0644 \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628 \u06a9\u06cc \u062a\u0641\u0631\u06cc\u0642 \u0633\u06d2 \u0628\u0627\u0644\u0627\u062a\u0631 \u06c1\u0648\u06a9\u0631 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u062d\u0642 \u0645\u06cc\u06ba \u0627\u0648\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u0633\u06cc \u0645\u0646\u0627\u0633\u0628\u062a \u0633\u06d2 \u06a9\u06cc\u0646\u06cc\u0688\u0627 \u06a9\u06d2...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/60901\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T21:07:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.mehrnews.com\/d\/2025\/03\/25\/4\/5436787.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645\",\"datePublished\":\"2025-03-25T21:07:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg\",\"articleSection\":[\"\u0639\u0627\u0644\u0645\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/60901#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/60901\",\"name\":\"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg\",\"datePublished\":\"2025-03-25T21:07:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/60901\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/60901#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/60901","og_locale":"en_US","og_type":"article","og_title":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -","og_description":"\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u06a9\u06cc \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u063a\u0632\u06c1 \u067e\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u0641\u0648\u0631\u0633\u0632 \u06a9\u06d2 \u062f\u0648\u0628\u0627\u0631\u06c1 \u062d\u0645\u0644\u06d2 \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0645\u062e\u062a\u0644\u0641 \u0645\u0642\u0627\u0645\u0627\u062a \u067e\u0631 \u0645\u0638\u0627\u06c1\u0631\u06d2 \u06c1\u0648\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0631\u0646\u06af\u060c \u0646\u0633\u0644 \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628 \u06a9\u06cc \u062a\u0641\u0631\u06cc\u0642 \u0633\u06d2 \u0628\u0627\u0644\u0627\u062a\u0631 \u06c1\u0648\u06a9\u0631 \u0641\u0644\u0633\u0637\u06cc\u0646\u06cc \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u062d\u0642 \u0645\u06cc\u06ba \u0627\u0648\u0631 \u0635\u06c1\u06cc\u0648\u0646\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u0633\u06cc \u0645\u0646\u0627\u0633\u0628\u062a \u0633\u06d2 \u06a9\u06cc\u0646\u06cc\u0688\u0627 \u06a9\u06d2...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/60901","article_published_time":"2025-03-25T21:07:31+00:00","og_image":[{"url":"https:\/\/media.mehrnews.com\/d\/2025\/03\/25\/4\/5436787.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645","datePublished":"2025-03-25T21:07:31+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg","articleSection":["\u0639\u0627\u0644\u0645\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/60901#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/60901","url":"https:\/\/safirnews.in\/urdu\/archives\/60901","name":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg","datePublished":"2025-03-25T21:07:31+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/60901"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/03\/5436787.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/60901#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u0641\u0644\u0633\u0637\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062d\u0636\u0631\u062a \u0639\u06cc\u0633\u06cc (\u0639) \u0627\u0648\u0631 \u0627\u0645\u0627\u0645 \u062d\u0633\u06cc\u0646 (\u0639) \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u06a9\u0627 \u062d\u0635\u06c1 \u06c1\u06d2\u060c \u06a9\u06cc\u0646\u06cc\u0688\u06cc\u0646 \u0648\u06a9\u06cc\u0644 \u0648 \u0635\u062d\u0627\u0641\u06cc \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/60901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=60901"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/60901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/60902"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=60901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=60901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=60901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}