{"id":56378,"date":"2025-02-28T11:55:54","date_gmt":"2025-02-28T11:55:54","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/56378"},"modified":"2025-02-28T11:55:54","modified_gmt":"2025-02-28T11:55:54","slug":"%d9%be%d8%a7%da%a9%d8%b3%d8%aa%d8%a7%d9%86%d8%8c-%d9%86%d9%85%d8%a7%d8%b2-%d8%ac%d9%85%d8%b9%db%81-%d9%85%db%8c%da%ba-%d8%ae%d9%88%d8%af%da%a9%d8%b4-%d8%af%da%be%d9%85%d8%a7%da%a9%d8%a7%d8%8c-%d9%85","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/56378","title":{"rendered":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/media.mehrnews.com\/d\/2025\/02\/28\/1\/5401793.jpg\" \/><\/p>\n<div itemprop=\"articleBody\">\n<p><strong>\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0<\/strong>\u0646\u06d2 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0646\u0642\u0644 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0622\u0626\u06cc \u062c\u06cc \u062e\u06cc\u0628\u0631 \u067e\u062e\u062a\u0648\u0646\u062e\u0648\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642 \u06c1\u0648\u0626\u06d2\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u0633\u06d2 \u0641\u0631\u0627\u0646\u0632\u06a9 \u0679\u06cc\u0645\u0648\u06ba \u0646\u06d2 \u0634\u0648\u0627\u06c1\u062f \u0627\u06a9\u0679\u06be\u06d2 \u06a9\u0631\u0644\u06cc\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u062a\u06d2 \u06c1\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06cc \u0628\u06be\u0627\u0631\u06cc \u0646\u0641\u0631\u06cc \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686\u06cc \u062c\u0628 \u06a9\u06c1 \u0627\u0645\u062f\u0627\u062f\u06cc \u0679\u06cc\u0645\u0648\u06ba \u0627\u0648\u0631 \u0645\u0642\u0627\u0645\u06cc \u0627\u0641\u0631\u0627\u062f \u0646\u06d2 \u0645\u0644\u0628\u06c1 \u06c1\u0679\u0627 \u06a9\u0631 \u0632\u062e\u0645\u06cc\u0648\u06ba \u06a9\u0648 \u0646\u06a9\u0627\u0644\u0627\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u062d\u06a9\u0627\u0645 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062f\u06be\u0645\u0627\u06a9\u0627 \u062e\u0648\u062f\u06a9\u0634 \u062a\u06be\u0627\u06d4<\/p>\n<p>\u0627\u06cc\u06a9\u0633\u067e\u0631\u06cc\u0633 \u0646\u06cc\u0648\u0632 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u06cc\u06a9 \u0633\u06cc\u0646\u0626\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0622\u0641\u06cc\u0633\u0631 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u06a9\u0648 \u0679\u0627\u0631\u06af\u0679 \u06a9\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0645\u0633\u062c\u062f \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0644\u062d\u0642\u06c1 \u0627\u06cc\u0631\u06cc\u0627 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u06a9\u0648 \u0646\u0634\u0627\u0646\u06c1 \u0628\u0646\u0627\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0627\u06a9\u0648\u0691\u06c1 \u062e\u0679\u06a9 \u0645\u062f\u0631\u0633\u06d2 \u0645\u06cc\u06ba \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 23 \u0627\u06c1\u0644 \u06a9\u0627\u0631 \u0688\u06cc\u0648\u0679\u06cc \u067e\u0631 \u062a\u0639\u06cc\u0646\u0627\u062a \u062a\u06be\u06d2\u06d4 \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u06a9\u0648 6 \u067e\u0648\u0644\u06cc\u0633 \u0627\u06c1\u0644 \u06a9\u0627\u0631 \u0633\u06a9\u06cc\u0648\u0631\u0679\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u06cc\u06d2 \u06af\u0626\u06d2 \u062a\u06be\u06d2\u06d4 \u0627\u06a9\u0648\u0691\u06c1 \u062e\u0679\u06a9 \u0645\u062f\u0631\u0633\u06d2 \u06a9\u06d2 \u0627\u0646\u0679\u0631\u06cc \u06af\u06cc\u0679\u0633 \u067e\u0631 \u0645\u062f\u0631\u0633\u06c1 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u06a9\u06cc \u0628\u06be\u06cc \u0633\u06a9\u06cc\u0648\u0631\u0679\u06cc \u0645\u0648\u062c\u0648\u062f \u062a\u06be\u06cc\u06d4<\/p>\n<p>\u0633\u06cc\u0646\u0679\u0631\u0644 \u067e\u0648\u0644\u06cc\u0633 \u0622\u0641\u0633 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u062c\u0627\u0631\u06cc \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u062a\u0635\u062f\u06cc\u0642 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0627\u06a9\u0648\u0691\u06c1 \u062e\u0679\u06a9 \u062f\u06be\u0645\u0627\u06a9\u0627 \u062e\u0648\u062f\u06a9\u0634 \u062a\u06be\u0627\u06d4 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc \u06c1\u0648\u0626\u06d2\u060c \u062c\u0648 \u0628\u0639\u062f \u0627\u0632\u0627\u06ba \u0632\u062e\u0645\u0648\u06ba \u06a9\u06cc \u062a\u0627\u0628 \u0646\u06c1 \u0644\u0627\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062c\u0627\u0646\u0628\u062d\u0642 \u06c1\u0648\u06af\u0626\u06d2\u06d4 \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u0645\u0633\u062c\u062f \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06af\u06cc\u0679 \u0633\u06d2 \u062f\u0627\u062e\u0644 \u06c1\u0648\u0627\u06d4 \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u0633\u06d2 \u0632\u062e\u0645\u06cc\u0648\u06ba \u06a9\u0648 \u0627\u0633\u067e\u062a\u0627\u0644 \u0645\u0646\u062a\u0642\u0644 \u06a9\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4<\/p>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u0646\u06d2 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0646\u0642\u0644 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0622\u0626\u06cc \u062c\u06cc \u062e\u06cc\u0628\u0631 \u067e\u062e\u062a\u0648\u0646\u062e\u0648\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642 \u06c1\u0648\u0626\u06d2\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u0633\u06d2 \u0641\u0631\u0627\u0646\u0632\u06a9 \u0679\u06cc\u0645\u0648\u06ba \u0646\u06d2 \u0634\u0648\u0627\u06c1\u062f \u0627\u06a9\u0679\u06be\u06d2 \u06a9\u0631\u0644\u06cc\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u062a\u06d2&#8230;<\/p>\n","protected":false},"author":1,"featured_media":56379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-56378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/56378\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -\" \/>\n<meta property=\"og:description\" content=\"\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u0646\u06d2 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0646\u0642\u0644 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0622\u0626\u06cc \u062c\u06cc \u062e\u06cc\u0628\u0631 \u067e\u062e\u062a\u0648\u0646\u062e\u0648\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642 \u06c1\u0648\u0626\u06d2\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u0633\u06d2 \u0641\u0631\u0627\u0646\u0632\u06a9 \u0679\u06cc\u0645\u0648\u06ba \u0646\u06d2 \u0634\u0648\u0627\u06c1\u062f \u0627\u06a9\u0679\u06be\u06d2 \u06a9\u0631\u0644\u06cc\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u062a\u06d2...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/56378\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T11:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.mehrnews.com\/d\/2025\/02\/28\/1\/5401793.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc\",\"datePublished\":\"2025-02-28T11:55:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg\",\"articleSection\":[\"\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/56378#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/56378\",\"name\":\"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg\",\"datePublished\":\"2025-02-28T11:55:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/56378\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/56378#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/56378","og_locale":"en_US","og_type":"article","og_title":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -","og_description":"\u0645\u06c1\u0631 \u062e\u0628\u0631\u0631\u0633\u0627\u06ba \u0627\u06cc\u062c\u0646\u0633\u06cc\u00a0\u0646\u06d2 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0646\u0642\u0644 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0622\u0626\u06cc \u062c\u06cc \u062e\u06cc\u0628\u0631 \u067e\u062e\u062a\u0648\u0646\u062e\u0648\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0645\u06cc\u06ba 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642 \u06c1\u0648\u0626\u06d2\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4 \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062c\u0627\u0626\u06d2 \u0648\u0642\u0648\u0639 \u0633\u06d2 \u0641\u0631\u0627\u0646\u0632\u06a9 \u0679\u06cc\u0645\u0648\u06ba \u0646\u06d2 \u0634\u0648\u0627\u06c1\u062f \u0627\u06a9\u0679\u06be\u06d2 \u06a9\u0631\u0644\u06cc\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062f\u06be\u0645\u0627\u06a9\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u062a\u06d2...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/56378","article_published_time":"2025-02-28T11:55:54+00:00","og_image":[{"url":"https:\/\/media.mehrnews.com\/d\/2025\/02\/28\/1\/5401793.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc","datePublished":"2025-02-28T11:55:54+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg","articleSection":["\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/56378#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/56378","url":"https:\/\/safirnews.in\/urdu\/archives\/56378","name":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg","datePublished":"2025-02-28T11:55:54+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/56378"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2025\/02\/5401793.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/56378#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0646\u0645\u0627\u0632 \u062c\u0645\u0639\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f\u06a9\u0634 \u062f\u06be\u0645\u0627\u06a9\u0627\u060c \u0645\u0648\u0644\u0627\u0646\u0627 \u062d\u0627\u0645\u062f \u0627\u0644\u062d\u0642 \u0633\u0645\u06cc\u062a 4 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0646 \u0628\u062d\u0642\u060c \u06a9\u0626\u06cc \u0634\u062f\u06cc\u062f \u0632\u062e\u0645\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/56378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=56378"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/56378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/56379"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=56378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=56378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=56378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}