{"id":39526,"date":"2024-12-09T07:34:37","date_gmt":"2024-12-09T07:34:37","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/39526"},"modified":"2024-12-09T07:34:37","modified_gmt":"2024-12-09T07:34:37","slug":"%d8%aa%d8%a7%d8%b1%db%8c%d8%ae-%da%a9%d9%88-%db%8c%d8%a7%d8%af-%d8%b1%da%a9%da%be%d9%86%d8%a7-%d8%b0%d9%85%db%81-%d8%af%d8%a7%d8%b1-%d9%82%d9%88%d9%85%d9%88%da%ba-%da%a9%db%8c-%d8%b9%d9%84%d8%a7","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/39526","title":{"rendered":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f  \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a"},"content":{"rendered":"<p>[]<br \/>\n<\/p>\n<div>\n<p>\u0627\u06c1\u0644 \u0641\u0644\u0633\u0637\u06cc\u0646 \u0633\u06d2 \u0633\u0628\u0642 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a\u06d4\u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u062c\u0644\u0633\u06c1 \u0633\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0634\u062e\u0635\u06cc\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u062e\u06cc\u0627\u0644<\/p>\n<p><strong>\u062d\u06cc\u062f\u0631 \u0622\u0628\u0627\u062f<\/strong>: \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u0627 \u06cc\u06c1 \u0634\u06cc\u0648\u06c1 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u067e\u0646\u06cc \u0627\u0635\u0644 \u062a\u0627\u0631\u06cc\u062e \u06a9\u0648\u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u062d\u0642 \u0628\u0627\u062a \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0646\u0626\u06cc \u0646\u0633\u0644 \u0645\u06cc\u06ba \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062a\u06cc \u06c1\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u0627\u0633\u06d2 \u0645\u0634\u0639\u0644 \u0631\u0627\u06c1 \u0628\u0646\u0627 \u06a9\u0631 \u0645\u0633\u062a\u0642\u0628\u0644 \u06a9\u0627 \u0633\u0641\u0631 \u0637\u0626\u06d2 \u06a9\u0631 \u0633\u06a9\u06d2 \u0634\u06c1\u0627\u062f\u062a \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u0627 \u0648\u0627\u0642\u0639\u06c1 \u0628\u06be\u06cc \u0645\u0633\u0644\u0645\u0627\u0646\u0627\u0646 \u06c1\u0646\u062f \u06a9\u06d2 \u0644\u0626\u06d2 \u0627\u06cc\u06a9 \u0633\u0631\u062e \u0644\u06a9\u06cc\u0631 \u06a9\u06cc \u062d\u06cc\u062b\u06cc\u062a \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2\u06d4 <\/p>\n<p>\u0627\u0633 \u067e\u06cc\u063a\u0627\u0645 \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0622\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0646\u0633\u0644\u0648\u06ba \u062a\u06a9 \u067e\u06c1\u0646\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u06a9\u0644 \u062c\u0645\u0627\u0639\u062a\u06cc \u0627\u062c\u0644\u0627\u0633 \u0639\u0627\u0645 \u0628\u0636\u0645\u0646 \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f\u062d\u0636\u0631\u062a \u0645\u0633\u062c\u062f \u0627\u064f\u062c\u0627\u0644\u06d2 \u0634\u0627\u06c1 \u0633\u0639\u06cc\u062f\u0622\u0628\u0627\u062f \u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f \u0645\u06cc\u06ba \u0631\u06a9\u06be\u0627 \u06af\u06cc\u0627\u06d4<\/p>\n<p>\u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06cc \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0644\u0626\u06d2 \u06c1\u0645\u06cc\u06ba \u0627\u06c1\u0644 \u0641\u0644\u0633\u0637\u06cc\u0646 \u0633\u06d2 \u0633\u0628\u0642 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u062c\u0633 \u0637\u0631\u062d \u0648\u06c1 \u0645\u0633\u0644\u0633\u0644 70 \u062a\u0627 80 \u0633\u0627\u0644 \u0633\u06d2 \u0642\u0631\u0628\u0627\u0646\u06cc\u0627\u06ba \u062f\u06d2 \u06a9\u0631 \u0645\u0633\u0644\u0633\u0644 \u0627\u0633 \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u067e\u0646\u0627 \u0633\u0628 \u06a9\u0686\u06be \u0644\u0679\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u2018\u00a0 \u0642\u0628\u0644\u06c1 \u0627\u0648\u0644 \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u06d2 \u0644\u0626\u06d2 \u0627\u067e\u0646\u06cc \u062c\u0627\u0646\u0648\u06ba \u06a9\u0627 \u0646\u0630\u0631\u0627\u0646\u06c1 \u067e\u06cc\u0634 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u2018 \u0627\u0633 \u0633\u06d2 \u06c1\u0645\u06cc\u06ba \u062f\u0631\u0633 \u0646\u0635\u06cc\u062d\u062a \u0644\u06cc\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4 <\/p>\n<p>\u06cc\u0648\u0645 \u0634\u06c1\u0627\u062f\u062a \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06d2 \u062c\u0644\u0633\u06d2 \u0633\u06d2 \u062e\u0637\u0627\u0628 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062c\u0646\u0627\u0628 \u0645\u0642\u06cc\u0645 \u0627\u0644\u062f\u06cc\u0646 \u06cc\u0627\u0633\u0631 \u0641\u0631\u0632\u0646\u062f \u0645\u0648\u0644\u0627\u0646\u0627 \u0646\u0635\u06cc\u0631\u0627\u0644\u062f\u06cc\u0646 \u0645\u0631\u062d\u0648\u0645 \u0646\u06d2 \u0627\u0646 \u062e\u06cc\u0627\u0644\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u06cc\u0627\u06d4 <\/p>\n<p>\u06cc\u06c1 \u062c\u0644\u0633\u06c1 \u0645\u0633\u062c\u062f \u062d\u0636\u0631\u062a \u0627\u064f\u062c\u0627\u0644\u06d2 \u0634\u0627\u06c1\u0612\u2018 \u0633\u0639\u06cc\u062f \u0622\u0628\u0627\u062f \u0645\u06cc\u06ba \u0648\u062d\u062f\u062a \u0627\u0633\u0644\u0627\u0645\u06cc \u06c1\u0646\u062f (\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f) \u06a9\u06d2 \u0632\u06cc\u0631 \u0627\u06c1\u062a\u0645\u0627\u0645 \u0645\u0646\u0639\u0642\u062f \u06c1\u0648\u0627 \u062c\u0633 \u0633\u06d2 \u0645\u062e\u062a\u0644\u0641 \u0639\u0644\u0645\u0627\u0621 \u0648 \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0646\u06d2 \u062e\u0637\u0627\u0628 \u06a9\u06cc\u0627\u06d4<\/p>\n<p> \u0635\u062f\u0631 \u062a\u062d\u0631\u06cc\u06a9 \u0645\u0633\u0644\u0645 \u0634\u0628\u0627\u0646 \u062c\u0646\u0627\u0628 \u0645\u0634\u062a\u0627\u0642 \u0645\u0644\u06a9 \u0646\u06d2 \u0627\u0644\u0644\u06c1 \u062a\u0639\u0627\u0644\u06cc \u067e\u0631 \u06a9\u0627\u0645\u0644 \u0628\u06be\u0631\u0648\u0633\u06c1 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0645\u06cc\u062f\u0627\u0646 \u0639\u0645\u0644 \u0645\u06cc\u06ba \u0688\u0679\u06d2 \u0631\u06c1\u0646\u06d2 \u06a9\u06cc \u062a\u0644\u0642\u06cc\u0646 \u06a9\u06cc \u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062d\u0627\u0644\u0627\u062a \u06a9\u0627 \u0631\u062e \u062f\u06cc\u06a9\u06be \u06a9\u0631\u06af\u06be\u0628\u0631\u0627\u0646\u06d2 \u06a9\u06cc \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0634\u06a9\u0633\u062a \u062e\u0648\u0631\u062f\u06af\u06cc \u0627\u0648\u0631 \u062e\u0648\u0641 \u06a9\u06cc \u06a9\u06cc\u0641\u06cc\u062a \u0633\u06d2 \u0646\u06a9\u0644\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4 <\/p>\n<p>\u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06d2 \u0641\u06cc\u0635\u0644\u06d2 \u0645\u06cc\u06ba\u00a0 \u062e\u0648 \u062f \u0639\u062f\u0627\u0644\u062a \u0646\u06d2 \u06cc\u06c1 \u0645\u0627\u0646\u0627 \u06a9\u06c1 \u0648\u06c1\u0627\u06ba \u06a9\u0648\u0626\u06cc \u0645\u0646\u062f\u0631 \u06a9\u0648 \u06af\u0631\u0627 \u06a9\u0631 \u0645\u0633\u062c\u062f \u0646\u06c1\u06cc\u06ba \u0628\u0646\u0627\u0626\u06cc \u06af\u0626\u06cc \u0627\u0648\u0631 \u0639\u062f\u0627\u0644\u062a \u0646\u06d2 \u0645\u0648\u0631\u062a\u06cc\u0648\u06ba \u06a9\u06d2 \u067e\u0631\u06a9\u0679 \u06c1\u0648\u0646\u06d2 (\u0644\u0627\u06a9\u0631 \u0631\u06a9\u06be\u0646\u06d2) \u06a9\u0648 \u062c\u0631\u0645 \u0642\u0631\u0627\u0631\u062f\u06cc\u0627\u06d4 <\/p>\n<p>\u0688\u0627\u06a9\u0679\u0631 \u062a\u0648\u0641\u06cc\u0642 \u0627\u062d\u0645\u062f \u0646\u0627\u0638\u0645 \u0648\u062d\u062f\u062a \u0627\u0633\u0644\u0627\u0645\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06cc\u06c1 \u0627\u0641\u0633\u0648\u0633 \u06a9\u0627 \u0645\u0642\u0627\u0645 \u06c1\u06d2 \u06a9\u06c1 \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0633\u0648\u0634\u06cc\u0644 \u0645\u06cc\u0688\u06cc\u0627 \u0628\u06be\u06cc \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06d2 \u062a\u0630\u06a9\u0631\u06c1 \u0633\u06d2 \u062e\u0627\u0644\u06cc \u06c1\u06cc\u06ba\u06d4<\/p>\n<p> \u06c1\u0645\u06cc\u06ba \u0627\u0633 \u0645\u0633\u0626\u0644\u06c1 \u06a9\u0648 \u0632\u0646\u062f\u06c1 \u0631\u06a9\u06be\u0646\u06d2 \u0627\u0648\u0631 \u0622\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0646\u0633\u0644\u0648\u06ba \u06a9\u0648 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06cc \u062d\u0642\u06cc\u0642\u062a \u0627\u0648\u0631 \u0646\u0627 \u0627\u0646\u0635\u0627\u0641\u06cc \u06a9\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0633\u06d2 \u0648\u0627\u0642\u0641 \u06a9\u0631\u0648\u0627\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4<\/p>\n<p> \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06cc \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0644\u0626\u06d2 \u06c1\u0645 \u062a\u062d\u0631\u06cc\u06a9 \u0686\u0644\u0627\u062a\u06d2 \u0631\u06c1\u06cc\u06ba \u06af\u06d2\u2018 \u0627\u0644\u0644\u06c1 \u06a9\u06cc \u0630\u0627\u062a \u0633\u06d2 \u06c1\u0645\u06cc\u06ba \u06c1\u0631 \u06af\u0632 \u0645\u0627\u06cc\u0648\u0633 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u0646\u0627 \u0686\u0627\u06c1\u06cc\u06d2 \u062e\u0648\u0627\u06c1 \u062d\u0627\u0644\u0627\u062a \u06a9\u062a\u0646\u06d2 \u06c1\u06cc \u0646\u0627 \u06af\u0641\u062a\u06c1 \u0628\u06c1 \u06a9\u06cc\u0648\u06ba \u0646\u06c1 \u06c1\u0648\u06ba\u06d4 <\/p>\n<p>\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u0627 \u062c\u0633 \u0648\u0642\u062a \u062a\u0646\u0627\u0632\u06c1 \u06c1\u0648\u0627 \u062a\u06be\u0627 \u062a\u0628 \u062d\u0642 \u067e\u0631\u0633\u062a \u0639\u0644\u0645\u0627 \u0648 \u062f\u0627\u0646\u0634\u0648\u0631\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u062a\u06be\u0627 \u06a9\u06c1 \u06cc\u06c1 \u0645\u0633\u0626\u0644\u06c1 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0631\u062e \u0644\u06a9\u06cc\u0631 \u06c1\u06d2 \u0627\u0648\u0631 \u0641\u06cc \u0627\u0644\u0648\u0627\u0642\u0639\u06cc \u0627\u06cc\u0633\u0627 \u06c1\u06cc \u062b\u0627\u0628\u062a \u06c1\u0648\u0627\u06d4\u00a0 \u0639\u0644\u0645\u0627 \u0648 \u062f\u0627\u0646\u0634\u0648\u0631\u06ba \u0646\u06d2 \u06cc\u06c1 \u0628\u06be\u06cc \u06a9\u06c1\u0627 \u062a\u06be\u0627 \u06a9\u06c1 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06cc \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0645\u0633\u0644\u0645\u0627\u0646\u0648\u06ba \u06a9\u06d2 \u0644\u0626\u06d2 \u0627\u06cc\u0645\u0627\u0646\u2018\u00a0 \u0639\u0632\u062a \u0648 \u0648\u0642\u0627\u0631 \u06a9\u0627 \u0645\u0633\u0626\u0644\u06c1 \u06c1\u06d2\u06d4 <\/p>\n<p>\u0645\u0633\u0644\u0645\u0627\u0646 \u0622\u062c \u0628\u06be\u06cc \u0627\u0633 \u0645\u0633\u0626\u0644\u06c1 \u06a9\u0648 \u0633\u06cc\u0646\u06d2 \u0633\u06d2 \u0644\u06af\u0627\u0626\u06d2 \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062c\u0646\u0627\u0628 \u0645\u062c\u0627\u06c1\u062f \u06c1\u0627\u0634\u0645\u06cc \u0646\u06d2 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06cc \u0634\u06c1\u0627\u062f\u062a \u06a9\u06d2 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u0648 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u0645\u06cc\u06ba \u062c\u0645\u06c1\u0648\u0631\u06cc\u062a \u06a9\u06d2 \u062e\u0627\u062a\u0645\u06c1 \u0627\u0648\u0631 \u06c1\u0646\u062f\u0648\u0631\u0627\u0634\u0679\u0631\u0627 \u06a9\u06cc \u0633\u0645\u062a \u0628\u0691\u06be\u062a\u06d2 \u0642\u062f\u0645 \u0633\u06d2 \u062c\u0648\u0691\u0627\u06d4 <\/p>\n<p>\u062f\u0631\u0633 \u06af\u0627\u06c1 \u062c\u06c1\u0627 \u062f\u0648 \u0634\u06c1\u0627\u062f\u062a \u06a9\u06d2 \u062c\u0646\u0627\u0628 \u062e\u0627\u0644\u062f \u0633\u06cc\u0641 \u0627\u0644\u0644\u06c1 \u0627\u06cc\u0688\u0648\u06a9\u06cc\u0679 \u0646\u06d2 \u0633\u06cc\u0631\u062a \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u06cc\u0627\u062f \u062f\u0644\u0627\u06cc\u0627 \u06a9\u06c1 \u0646\u0628\u06cc \u0645\u06a9\u0631\u0645 \ufdfa \u06a9\u0648 \u06a9\u0639\u0628\u06c3 \u0627\u0644\u0644\u06c1 \u0645\u06cc\u06ba \u062f\u0627\u062e\u0644\u06d2 \u0633\u06d2 \u0631\u0648\u06a9\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u062f\u0634\u0645\u0646\u0648\u06ba \u06a9\u06d2 \u0627\u0633 \u0627\u0642\u062f\u0627\u0645 \u0646\u06d2 \u0641\u062a\u062d \u0645\u06a9\u06c1 \u06a9\u0627 \u062f\u0631\u0648\u0627\u0632\u06c1 \u06a9\u06be\u0648\u0644\u0627\u2018 \u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062d\u0627\u062f\u062b\u0627\u062a \u0627\u0648\u0631 \u0622\u0632\u0645\u0627\u0626\u0634\u06cc\u06ba \u0642\u0648\u0645\u0648\u06ba \u06a9\u0648 \u062e\u0648\u0627\u0628 \u063a\u0641\u0644\u062a \u0633\u06d2 \u0628\u06cc\u062f\u0627\u0631 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u0631\u0648\u0646\u0645\u0627 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<\/p>\n<p> \u06c1\u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u0631\u0628 \u06a9\u06cc \u0637\u0631\u0641 \u062f\u06cc\u0646 \u06a9\u06cc \u0637\u0631\u0641 \u0627\u0648\u0631 \u0631\u06c1\u0628\u0631 \u0648\u0631\u06c1 \u0646\u0645\u0627 \u0646\u0628\u06cc \u0645\u0639\u0638\u0645 \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u0628\u0639\u062b\u062a \u06a9\u06d2 \u0645\u0642\u0635\u062f \u06a9\u06cc \u0637\u0631\u0641 \u067e\u0644\u0679\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4 <\/p>\n<p>\u0627\u0633 \u0645\u0648\u0642\u0639 \u067e\u0631 \u062c\u0646\u0627\u0628 \u0645\u0646\u06cc\u0631 \u0627\u0644\u062f\u06cc\u0646 \u0645\u062c\u0627\u06c1\u062f (\u062a\u0646\u0638\u06cc\u0645 \u062e\u06cc\u0631 \u0627\u064f\u0645\u062a) \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0642\u06cc\u0627\u062f\u062a\u0648\u06ba \u0646\u06d2 \u0628\u0627\u0628\u0631\u06cc \u0645\u0633\u062c\u062f \u06a9\u06d2 \u0645\u0639\u0627\u0644\u0645\u06d2 \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06d2 \u0628\u06be\u06cc \u0627\u0648\u0631 \u0627\u0628 \u0628\u06be\u06cc \u0645\u0627\u06cc\u0648\u0633 \u06a9\u06cc\u0627\u2018 \u0645\u0648\u0644\u0648\u06cc \u0645\u062d\u0645\u062f \u0634\u0639\u06cc\u0628 \u0627\u0644\u062f\u06cc\u0646 \u06a9\u06cc \u0642\u0631\u0623\u062a \u06a9\u0644\u0627\u0645 \u067e\u0627\u06a9 \u0633\u06d2 \u0627\u0633 \u062c\u0644\u0633\u06c1 \u06a9\u0627 \u0622\u063a\u0627\u0632 \u06c1\u0648\u0627\u06d4<\/p>\n<p> \u0627\u0633 \u0645\u0648\u0642\u0639 \u067e\u0631 \u0646\u0627\u0638\u0645 \u0648\u062d\u062f\u062a \u062a\u0644\u0646\u06af\u0627\u0646\u06c1 \u0688\u0627\u06a9\u0679\u0631 \u062a\u0648\u0641\u06cc\u0642 \u0646\u06d2 \u062a\u0631\u0627\u0646\u06c1 \u067e\u0691\u06be\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0633\u0627\u0645\u0639\u06cc\u0646 \u06a9\u0648\u06af\u0631\u0645\u0627\u062f\u06cc\u0627\u06d4<\/p>\n<p>\n\t\t\t<input type=\"text\" id=\"short-post-url\" value=\"urdu.munsifdaily.com\/?p=172179\" data-url=\"https:\/\/urdu.munsifdaily.com\/?p=172179\"\/><br \/>\n\t\t\t<button type=\"button\" id=\"copy-post-url\" class=\"button\">Copy URL<\/button><br \/>\n\t\t\t<span id=\"copy-post-url-msg\" style=\"display:none;\">URL Copied<\/span>\n\t\t<\/p>\n<\/p><\/div>\n<div>\n<p>\u06c1\u0645\u06cc\u06ba \u0641\u0627\u0644\u0648 \u06a9\u0631\u06cc\u06ba<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKML3oqQswr_PBAw?ceid=IN:en&amp;oc=3\" title=\"Google News\" target=\"_blank\" rel=\"nofollow noopener\" class=\"post-followus-btn google-new-btn\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/urdu.munsifdaily.com\/wp-content\/themes\/jannah\/assets\/images\/google-news.svg\" alt=\"Google News\" loading=\"lazy\" width=\"120\" height=\"22\"\/><br \/>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[] \u0627\u06c1\u0644 \u0641\u0644\u0633\u0637\u06cc\u0646 \u0633\u06d2 \u0633\u0628\u0642 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a\u06d4\u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u062c\u0644\u0633\u06c1 \u0633\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0634\u062e\u0635\u06cc\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u062e\u06cc\u0627\u0644 \u062d\u06cc\u062f\u0631 \u0622\u0628\u0627\u062f: \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u0627 \u06cc\u06c1 \u0634\u06cc\u0648\u06c1 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u067e\u0646\u06cc \u0627\u0635\u0644 \u062a\u0627\u0631\u06cc\u062e \u06a9\u0648\u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u062d\u0642 \u0628\u0627\u062a \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0646\u0626\u06cc \u0646\u0633\u0644 \u0645\u06cc\u06ba \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062a\u06cc \u06c1\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u0627\u0633\u06d2 \u0645\u0634\u0639\u0644 \u0631\u0627\u06c1 \u0628\u0646\u0627 \u06a9\u0631 \u0645\u0633\u062a\u0642\u0628\u0644 \u06a9\u0627 \u0633\u0641\u0631&#8230;<\/p>\n","protected":false},"author":1,"featured_media":39527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-39526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hyderabad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/39526\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -\" \/>\n<meta property=\"og:description\" content=\"[] \u0627\u06c1\u0644 \u0641\u0644\u0633\u0637\u06cc\u0646 \u0633\u06d2 \u0633\u0628\u0642 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a\u06d4\u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u062c\u0644\u0633\u06c1 \u0633\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0634\u062e\u0635\u06cc\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u062e\u06cc\u0627\u0644 \u062d\u06cc\u062f\u0631 \u0622\u0628\u0627\u062f: \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u0627 \u06cc\u06c1 \u0634\u06cc\u0648\u06c1 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u067e\u0646\u06cc \u0627\u0635\u0644 \u062a\u0627\u0631\u06cc\u062e \u06a9\u0648\u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u062d\u0642 \u0628\u0627\u062a \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0646\u0626\u06cc \u0646\u0633\u0644 \u0645\u06cc\u06ba \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062a\u06cc \u06c1\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u0627\u0633\u06d2 \u0645\u0634\u0639\u0644 \u0631\u0627\u06c1 \u0628\u0646\u0627 \u06a9\u0631 \u0645\u0633\u062a\u0642\u0628\u0644 \u06a9\u0627 \u0633\u0641\u0631...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/39526\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T07:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/urdu.munsifdaily.com\/wp-content\/themes\/jannah\/assets\/images\/google-news.svg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a\",\"datePublished\":\"2024-12-09T07:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg\",\"articleSection\":[\"\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/39526#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/39526\",\"name\":\"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg\",\"datePublished\":\"2024-12-09T07:34:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/39526\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg\",\"width\":780,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39526#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/39526","og_locale":"en_US","og_type":"article","og_title":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -","og_description":"[] \u0627\u06c1\u0644 \u0641\u0644\u0633\u0637\u06cc\u0646 \u0633\u06d2 \u0633\u0628\u0642 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a\u06d4\u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u062c\u0644\u0633\u06c1 \u0633\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0634\u062e\u0635\u06cc\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u062e\u06cc\u0627\u0644 \u062d\u06cc\u062f\u0631 \u0622\u0628\u0627\u062f: \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u0627 \u06cc\u06c1 \u0634\u06cc\u0648\u06c1 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u067e\u0646\u06cc \u0627\u0635\u0644 \u062a\u0627\u0631\u06cc\u062e \u06a9\u0648\u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u062d\u0642 \u0628\u0627\u062a \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0646\u0626\u06cc \u0646\u0633\u0644 \u0645\u06cc\u06ba \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062a\u06cc \u06c1\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u0627\u0633\u06d2 \u0645\u0634\u0639\u0644 \u0631\u0627\u06c1 \u0628\u0646\u0627 \u06a9\u0631 \u0645\u0633\u062a\u0642\u0628\u0644 \u06a9\u0627 \u0633\u0641\u0631...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/39526","article_published_time":"2024-12-09T07:34:37+00:00","og_image":[{"url":"https:\/\/urdu.munsifdaily.com\/wp-content\/themes\/jannah\/assets\/images\/google-news.svg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a","datePublished":"2024-12-09T07:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg","articleSection":["\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/39526#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/39526","url":"https:\/\/safirnews.in\/urdu\/archives\/39526","name":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg","datePublished":"2024-12-09T07:34:37+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/39526"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/112.jpg","width":780,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/39526#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u062a\u0627\u0631\u06cc\u062e \u06a9\u0648 \u06cc\u0627\u062f \u0631\u06a9\u06be\u0646\u0627 \u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0648\u0645\u0648\u06ba \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/39526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=39526"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/39526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/39527"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=39526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=39526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=39526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}