{"id":39088,"date":"2024-12-05T15:12:33","date_gmt":"2024-12-05T15:12:33","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/?p=39088"},"modified":"2024-12-05T15:12:33","modified_gmt":"2024-12-05T15:12:33","slug":"%d8%a7%d9%82%d8%a8%d8%a7%d9%84-%da%a9%d8%a7-%d9%be%db%8c%d8%ba%d8%a7%d9%85-%d9%86%d8%b8%d8%b1%db%8c%d8%a7%d8%aa%db%8c-%d9%be%d9%88%d9%84%d8%b1%d8%a7%d8%a6%d8%b2%db%8c%d8%b4%d9%86-%d8%a7%d9%88%d8%b1","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/39088","title":{"rendered":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4"},"content":{"rendered":"<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f\u060c 4 \u062f\u0633\u0645\u0628\u0631:<br \/>\n\u0645\u06cc\u0688\u06cc\u0627 \u067e\u0644\u0633 \u0622\u0688\u06cc\u0679\u0648\u0631\u06cc\u0645 \u0645\u06cc\u06ba &#8221;\u0645\u0648\u062c\u0648\u062f\u06c1 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u0639\u0644\u0627\u0645\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06cc \u0645\u0646\u0627\u0633\u0628\u062a&#8221; \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u0627\u06cc\u06a9 \u062a\u0648\u0633\u06cc\u0639\u06cc \u0644\u06cc\u06a9\u0686\u0631 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06c1\u0648\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0645\u0634\u06c1\u0648\u0631 \u0639\u0627\u0644\u0645\u060c \u0634\u0627\u0639\u0631 \u0627\u0648\u0631 \u0646\u0642\u0627\u062f \u0688\u0627\u06a9\u0679\u0631 \u062a\u0642\u06cc \u0639\u0627\u0628\u062f\u06cc \u0646\u06d2 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0641\u0644\u0633\u0641\u06d2 \u0627\u0648\u0631 \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u067e\u0631 \u062a\u0641\u0635\u06cc\u0644\u06cc \u06af\u0641\u062a\u06af\u0648 \u06a9\u06cc\u06d4<\/p>\n<p>\u062a\u0642\u0631\u06cc\u0628 \u0645\u06cc\u06ba \u0627\u062f\u0628 \u0627\u0648\u0631 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0634\u0627\u0626\u0642\u06cc\u0646\u060c \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0627\u0648\u0631 \u0627\u06c1\u0645 \u0634\u062e\u0635\u06cc\u0627\u062a \u0646\u06d2 \u0634\u0631\u06a9\u062a \u06a9\u06cc\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0688\u0627\u06a9\u0679\u0631 \u0631\u0624\u0641 \u062e\u06cc\u0631\u060c \u062c\u0639\u0641\u0631 \u062d\u0633\u06cc\u0646 (\u0627\u06cc\u0688\u06cc\u0679\u0631 \u0635\u062f\u0627\u0626\u06d2 \u062d\u0633\u06cc\u0646\u06cc)\u060c \u062c\u06d2 \u0627\u06cc\u0633 \u0627\u0641\u062a\u062e\u0627\u0631 (\u062c\u0631\u0646\u0644\u0633\u0679)\u060c \u0688\u0627\u06a9\u0679\u0631 \u0646\u0627\u0638\u0645 \u0639\u0644\u06cc\u060c \u0688\u0627\u06a9\u0679\u0631 \u062c\u0627\u0648\u06cc\u062f \u06a9\u0645\u0627\u0644\u060c \u0634\u0627\u06c1\u062f \u0632\u0628\u06cc\u0631\u06cc\u060c \u0627\u0648\u0631 \u0688\u0627\u06a9\u0679\u0631 \u0641\u0631\u06cc\u062f \u0627\u0644\u062f\u06cc\u0646 \u0635\u0627\u062f\u0642 \u0634\u0627\u0645\u0644 \u062a\u06be\u06d2\u06d4<\/p>\n<p>\u0688\u0627\u06a9\u0679\u0631 \u062a\u0642\u06cc \u0639\u0627\u0628\u062f\u06cc \u0646\u06d2 \u0639\u0644\u0627\u0645\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0641\u0644\u0633\u0641\u06c1 &#8220;\u062e\u0648\u062f\u06cc&#8221; \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc\u062a \u06a9\u06d2 \u0627\u062d\u062a\u0631\u0627\u0645 \u067e\u0631 \u0631\u0648\u0634\u0646\u06cc \u0688\u0627\u0644\u06cc\u060c \u06cc\u06c1 \u0628\u062a\u0627\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1 \u0627\u0646 \u06a9\u06d2 \u0646\u0638\u0631\u06cc\u0627\u062a \u0639\u0627\u0644\u0645\u06cc \u0627\u0645\u0646 \u0627\u0648\u0631 \u0627\u062a\u062d\u0627\u062f \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u06cc\u06a9 \u0631\u06c1\u0646\u0645\u0627 \u0627\u0635\u0648\u0644 \u06c1\u06cc\u06ba\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0633 \u0628\u0627\u062a \u067e\u0631 \u0632\u0648\u0631 \u062f\u06cc\u0627 \u06a9\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4<\/p>\n<p>\u0627\u0633 \u0645\u0648\u0642\u0639 \u067e\u0631 \u0688\u0627\u06a9\u0679\u0631 \u062e\u0627\u0644\u062f \u0634\u06c1\u0628\u0627\u0632 \u0646\u06d2 \u0627\u067e\u0646\u06cc \u062a\u0635\u0646\u06cc\u0641 &#8220;\u06a9\u0648\u06c1 \u0646\u0648\u0631\u0633&#8221; \u0688\u0627\u06a9\u0679\u0631 \u0639\u0627\u0628\u062f\u06cc \u06a9\u0648 \u067e\u06cc\u0634 \u06a9\u06cc\u060c \u062c\u0628\u06a9\u06c1 \u0634\u0627\u06c1\u062f \u0632\u0628\u06cc\u0631\u06cc \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0627\u0646\u06af\u0631\u06cc\u0632\u06cc \u06a9\u062a\u0627\u0628 \u06a9\u0627 \u062a\u062d\u0641\u06c1 \u062f\u06cc\u0627\u06d4 \u0688\u0627\u06a9\u0679\u0631 \u0641\u0631\u06cc\u062f \u0627\u0644\u062f\u06cc\u0646 \u0635\u0627\u062f\u0642 \u0646\u06d2 \u06af\u0644\u067e\u0648\u0634\u06cc \u06a9\u06cc \u0627\u0648\u0631 \u0639\u0627\u0645\u0631 \u062d\u0646\u06cc\u0641 \u0646\u06d2 \u06a9\u0627\u0631\u0631\u0648\u0627\u0626\u06cc \u06a9\u06cc\u06d4 \u0634\u06a9\u0631\u06cc\u06c1 \u0645\u062d\u06cc \u0627\u0644\u062f\u06cc\u0646 \u0646\u06d2 \u0627\u062f\u0627 \u06a9\u06cc\u0627\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f\u060c 4 \u062f\u0633\u0645\u0628\u0631: \u0645\u06cc\u0688\u06cc\u0627 \u067e\u0644\u0633 \u0622\u0688\u06cc\u0679\u0648\u0631\u06cc\u0645 \u0645\u06cc\u06ba &#8221;\u0645\u0648\u062c\u0648\u062f\u06c1 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u0639\u0644\u0627\u0645\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06cc \u0645\u0646\u0627\u0633\u0628\u062a&#8221; \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u0627\u06cc\u06a9 \u062a\u0648\u0633\u06cc\u0639\u06cc \u0644\u06cc\u06a9\u0686\u0631 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06c1\u0648\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0645\u0634\u06c1\u0648\u0631 \u0639\u0627\u0644\u0645\u060c \u0634\u0627\u0639\u0631 \u0627\u0648\u0631 \u0646\u0642\u0627\u062f \u0688\u0627\u06a9\u0679\u0631 \u062a\u0642\u06cc \u0639\u0627\u0628\u062f\u06cc \u0646\u06d2 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0641\u0644\u0633\u0641\u06d2 \u0627\u0648\u0631 \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u067e\u0631 \u062a\u0641\u0635\u06cc\u0644\u06cc \u06af\u0641\u062a\u06af\u0648 \u06a9\u06cc\u06d4 \u062a\u0642\u0631\u06cc\u0628 \u0645\u06cc\u06ba \u0627\u062f\u0628 \u0627\u0648\u0631 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0634\u0627\u0626\u0642\u06cc\u0646\u060c \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0627\u0648\u0631 \u0627\u06c1\u0645 \u0634\u062e\u0635\u06cc\u0627\u062a \u0646\u06d2&#8230;<\/p>\n","protected":false},"author":1,"featured_media":39089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,11],"tags":[],"class_list":["post-39088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest","category-hyderabad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/39088\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -\" \/>\n<meta property=\"og:description\" content=\"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f\u060c 4 \u062f\u0633\u0645\u0628\u0631: \u0645\u06cc\u0688\u06cc\u0627 \u067e\u0644\u0633 \u0622\u0688\u06cc\u0679\u0648\u0631\u06cc\u0645 \u0645\u06cc\u06ba &#8221;\u0645\u0648\u062c\u0648\u062f\u06c1 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u0639\u0644\u0627\u0645\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06cc \u0645\u0646\u0627\u0633\u0628\u062a&#8221; \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u0627\u06cc\u06a9 \u062a\u0648\u0633\u06cc\u0639\u06cc \u0644\u06cc\u06a9\u0686\u0631 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06c1\u0648\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0645\u0634\u06c1\u0648\u0631 \u0639\u0627\u0644\u0645\u060c \u0634\u0627\u0639\u0631 \u0627\u0648\u0631 \u0646\u0642\u0627\u062f \u0688\u0627\u06a9\u0679\u0631 \u062a\u0642\u06cc \u0639\u0627\u0628\u062f\u06cc \u0646\u06d2 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0641\u0644\u0633\u0641\u06d2 \u0627\u0648\u0631 \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u067e\u0631 \u062a\u0641\u0635\u06cc\u0644\u06cc \u06af\u0641\u062a\u06af\u0648 \u06a9\u06cc\u06d4 \u062a\u0642\u0631\u06cc\u0628 \u0645\u06cc\u06ba \u0627\u062f\u0628 \u0627\u0648\u0631 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0634\u0627\u0626\u0642\u06cc\u0646\u060c \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0627\u0648\u0631 \u0627\u06c1\u0645 \u0634\u062e\u0635\u06cc\u0627\u062a \u0646\u06d2...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/39088\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T15:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1507\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4\",\"datePublished\":\"2024-12-05T15:12:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg\",\"articleSection\":[\"\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba\",\"\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/39088#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/39088\",\"name\":\"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg\",\"datePublished\":\"2024-12-05T15:12:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/39088\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg\",\"width\":1507,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/39088#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/39088","og_locale":"en_US","og_type":"article","og_title":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -","og_description":"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f\u060c 4 \u062f\u0633\u0645\u0628\u0631: \u0645\u06cc\u0688\u06cc\u0627 \u067e\u0644\u0633 \u0622\u0688\u06cc\u0679\u0648\u0631\u06cc\u0645 \u0645\u06cc\u06ba &#8221;\u0645\u0648\u062c\u0648\u062f\u06c1 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u0639\u0644\u0627\u0645\u06c1 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06cc \u0645\u0646\u0627\u0633\u0628\u062a&#8221; \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u0627\u06cc\u06a9 \u062a\u0648\u0633\u06cc\u0639\u06cc \u0644\u06cc\u06a9\u0686\u0631 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06c1\u0648\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0645\u0634\u06c1\u0648\u0631 \u0639\u0627\u0644\u0645\u060c \u0634\u0627\u0639\u0631 \u0627\u0648\u0631 \u0646\u0642\u0627\u062f \u0688\u0627\u06a9\u0679\u0631 \u062a\u0642\u06cc \u0639\u0627\u0628\u062f\u06cc \u0646\u06d2 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0641\u0644\u0633\u0641\u06d2 \u0627\u0648\u0631 \u062a\u0639\u0644\u06cc\u0645\u0627\u062a \u067e\u0631 \u062a\u0641\u0635\u06cc\u0644\u06cc \u06af\u0641\u062a\u06af\u0648 \u06a9\u06cc\u06d4 \u062a\u0642\u0631\u06cc\u0628 \u0645\u06cc\u06ba \u0627\u062f\u0628 \u0627\u0648\u0631 \u0627\u0642\u0628\u0627\u0644 \u06a9\u06d2 \u0634\u0627\u0626\u0642\u06cc\u0646\u060c \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0627\u0648\u0631 \u0627\u06c1\u0645 \u0634\u062e\u0635\u06cc\u0627\u062a \u0646\u06d2...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/39088","article_published_time":"2024-12-05T15:12:33+00:00","og_image":[{"width":1507,"height":708,"url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4","datePublished":"2024-12-05T15:12:33+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg","articleSection":["\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba","\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/39088#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/39088","url":"https:\/\/safirnews.in\/urdu\/archives\/39088","name":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg","datePublished":"2024-12-05T15:12:33+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/39088"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2024\/12\/IMG-20241205-WA0114.jpg","width":1507,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/39088#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u0627\u0642\u0628\u0627\u0644 \u06a9\u0627 \u067e\u06cc\u063a\u0627\u0645 \u0646\u0638\u0631\u06cc\u0627\u062a\u06cc \u067e\u0648\u0644\u0631\u0627\u0626\u0632\u06cc\u0634\u0646 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u0631\u062a\u06cc \u0639\u062f\u0645 \u0645\u0633\u0627\u0648\u0627\u062a \u062c\u06cc\u0633\u06d2 \u0645\u0648\u062c\u0648\u062f\u06c1 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0627\u06c1 \u062d\u0644 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/39088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=39088"}],"version-history":[{"count":1,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/39088\/revisions"}],"predecessor-version":[{"id":39090,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/39088\/revisions\/39090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/39089"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=39088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=39088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=39088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}