{"id":121478,"date":"2026-05-12T11:03:28","date_gmt":"2026-05-12T11:03:28","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/121478"},"modified":"2026-05-12T11:03:28","modified_gmt":"2026-05-12T11:03:28","slug":"%d9%85%d9%88%da%88%db%8c%d8%b2-%d8%b1%db%8c%d9%b9%d9%86%da%af%d8%b2-%d9%86%db%92-%db%81%d9%86%d8%af%d9%88%d8%b3%d8%aa%d8%a7%d9%86-%da%a9%db%8c-%d8%a7%d9%82%d8%aa%d8%b5%d8%a7%d8%af","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/121478","title":{"rendered":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc"},"content":{"rendered":"<p><\/p>\n<div xmlns:default=\"http:\/\/www.w3.org\/2000\/svg\">\n<p><h2 class=\"styles-m__urdu-story-sub-title__3RVhM\">\u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0645\u0646\u0638\u0631 \u0646\u0627\u0645\u06c1 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u0631\u06cc\u06a9\u06c1-\u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0646\u0627\u0632\u06a9 \u06c1\u06d2\u06d4 \u06c1\u0645 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u062a\u06a9 \u06a9\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<\/h2>\n<\/p>\n<div class=\"styles-m__hero-image-wrapper__3m0Jr\">\n<figure class=\"qt-image-dynamic\"><picture class=\"qt-image\"><img decoding=\"async\" src=\"https:\/\/cf-images.assettype.com\/qaumiawaz%2F2023-06%2Fdf0ff498-90ae-43b5-8b86-815c17fd631b%2FMoodys_IA.jpg?rect=0%2C0%2C1500%2C844&amp;auto=format%2Ccompress&amp;fmt=webp\" type=\"image\/webp\" alt=\"&lt;div class=&quot;paragraphs&quot;&gt;&lt;p&gt;\u0645\u0648\u0688\u06cc\u0632\u060c \u062a\u0635\u0648\u06cc\u0631 \u0622\u0626\u06cc \u0627\u06d2 \u0627\u06cc\u0646 \u0627\u06cc\u0633&lt;\/p&gt;&lt;\/div&gt;\" class=\"qt-image\"\/><img decoding=\"async\" src=\"https:\/\/cf-images.assettype.com\/qaumiawaz%2F2023-06%2Fdf0ff498-90ae-43b5-8b86-815c17fd631b%2FMoodys_IA.jpg?rect=0%2C0%2C1500%2C844&amp;auto=format%2Ccompress&amp;fmt=webp&amp;w=1200\" alt=\"&lt;div class=&quot;paragraphs&quot;&gt;&lt;p&gt;\u0645\u0648\u0688\u06cc\u0632\u060c \u062a\u0635\u0648\u06cc\u0631 \u0622\u0626\u06cc \u0627\u06d2 \u0627\u06cc\u0646 \u0627\u06cc\u0633&lt;\/p&gt;&lt;\/div&gt;\"\/><\/picture>\n<p>i<\/p>\n<\/figure>\n<\/div>\n<div class=\"styles-m__story-body__3CVbF\">\n<div class=\"styles-m__urdu-story-content__TmZab\">\n<div class=\"styles-m__author-wrapper__17xTa\">\n<div>\n<div class=\"styles-m__author__29oEE\">\n<div class=\"styles-m__urdu-author-avatar__1cXY8\"><img decoding=\"async\" src=\"https:\/\/fea.assettype.com\/nationalherald\/assets\/user-dd606edb720ccbd76a44.svg\" alt=\"user\"\/><\/div>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.google.com\/preferences\/source?q=qaumiawaz.com\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"styles-m__google-badge__1VxwO styles-m__google-ur__23bfB\" src=\"https:\/\/images.assettype.com\/qaumiawaz\/2026-05-06\/kafsrlyy\/googlepreferredbadgeQA.png\" alt=\"google_preferred_badge\"\/><\/a><\/div>\n<div class=\"story-page-card urdu-story-justify\">\n<div class=\"\">\n<div class=\"story-element story-element-text\">\n<div>\n<p>\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632 \u0646\u06d2 2026 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 \u06a9\u0627 \u062a\u062e\u0645\u06cc\u0646\u06c1 \u0645\u0646\u06af\u0644 (12 \u0645\u0626\u06cc) \u06a9\u0648 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u06af\u06be\u0679\u0627 \u06a9\u0631 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc\u0627\u06d4 \u06cc\u06c1 \u06af\u0631\u0627\u0648\u0679 \u0646\u062c\u06cc \u06a9\u06be\u067e\u062a \u0627\u0648\u0631 \u0635\u0646\u0639\u062a\u06cc \u0633\u0631\u06af\u0631\u0645\u06cc\u0648\u06ba \u0645\u06cc\u06ba \u0633\u0633\u062a\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u062a\u0648\u0627\u0646\u0627\u0626\u06cc \u06a9\u06cc \u0628\u0644\u0646\u062f \u0644\u0627\u06af\u062a \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4 \u06a9\u0631\u06cc\u0688\u0679 \u0631\u06cc\u0679\u0646\u06af \u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u2019\u06af\u0644\u0648\u0628\u0644 \u0645\u06cc\u06a9\u0631\u0648 \u0622\u0624\u0679 \u0644\u064f\u06a9\u2018 \u06a9\u06d2 \u0645\u0626\u06cc \u0627\u06cc\u0688\u06cc\u0634\u0646 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u0622\u0626\u0646\u062f\u06c1 6 \u0645\u0627\u06c1 \u0645\u06cc\u06ba \u062a\u0648\u0627\u0646\u0627\u0626\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u0627\u0648\u0631 \u0627\u06cc\u0646\u062f\u06be\u0646 \u0648 \u06a9\u06be\u0627\u062f \u06a9\u06cc \u06a9\u0645\u06cc \u06a9\u0627 \u0627\u062b\u0631 \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0627\u0644\u06af \u0627\u0644\u06af \u06c1\u0648\u06af\u0627 \u062c\u0648 \u0627\u0646 \u06a9\u06d2 \u0627\u0646\u062d\u0635\u0627\u0631 \u0627\u0648\u0631 \u0644\u0686\u06a9 \u067e\u0631 \u0645\u0646\u062d\u0635\u0631 \u06c1\u06d2\u06d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"story-page-card urdu-story-justify\">\n<div class=\"\">\n<div class=\"story-element story-element-text\">\n<div>\n<p>\u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u2019\u2019\u0639\u0627\u0644\u0645\u06cc \u0645\u0646\u0638\u0631 \u0646\u0627\u0645\u06c1 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u0631\u06cc\u06a9\u06c1 \u0627\u0648\u0631 \u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0646\u0627\u0632\u06a9 \u06c1\u06d2\u06d4 \u06c1\u0645 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u062a\u06a9 \u06a9\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\u2018\u2018 \u0627\u0633 \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 2027 (\u06a9\u06cc\u0644\u0646\u0688\u0631 \u0633\u0627\u0644) \u06a9\u06d2 \u0644\u06cc\u06d2 \u0628\u06be\u06cc \u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0633 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u062c\u06cc \u0688\u06cc \u067e\u06cc (\u0645\u062c\u0645\u0648\u0639\u06cc \u0645\u0644\u06a9\u06cc \u067e\u06cc\u062f\u0627\u0648\u0627\u0631) \u06a9\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 \u06a9\u0627 \u062a\u062e\u0645\u06cc\u0646\u06c1 0.5 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u06af\u06be\u0679\u0627 \u06a9\u0631 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u06d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/p>\n<div class=\"story-page-card urdu-story-justify\">\n<div class=\"\">\n<div class=\"story-element story-element-text\">\n<div>\n<p>\u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062a\u0648\u0627\u0646\u0627\u0626\u06cc \u06a9\u06cc \u0633\u067e\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u0628\u06c1\u062a\u0631\u06cc \u0627\u0648\u0631 \u0634\u067e\u0646\u06af \u06a9\u06cc \u0622\u0645\u062f \u0648 \u0631\u0641\u062a \u06a9\u06d2 \u0645\u0639\u0645\u0648\u0644 \u067e\u0631 \u0622\u0646\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06cc\u06c1 \u062f\u0628\u0627\u0624 \u0622\u06c1\u0633\u062a\u06c1 \u0622\u06c1\u0633\u062a\u06c1 \u06a9\u0645 \u06c1\u0648\u06ba \u06af\u06d2 \u0627\u0648\u0631 \u0645\u0639\u0627\u0634\u06cc \u0633\u0631\u06af\u0631\u0645\u06cc\u0648\u06ba \u0645\u06cc\u06ba \u0628\u06c1\u062a\u0631\u06cc \u0622\u0626\u06d2 \u06af\u06cc\u06d4 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0645\u0648\u0688\u06cc\u0632 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06c1\u0646\u062f\u0648\u0648\u0633\u062a\u0627\u0646 \u062a\u06cc\u0644 \u06a9\u06cc \u0628\u0644\u0646\u062f \u0642\u06cc\u0645\u062a\u0648\u06ba \u06a9\u06d2 \u062a\u0626\u06cc\u06ba \u062e\u0635\u0648\u0635\u06cc \u0637\u0648\u0631 \u067e\u0631 \u062d\u0633\u0627\u0633 \u06c1\u06d2\u060c \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0645\u0644\u06a9 \u0627\u067e\u0646\u06cc \u062a\u0648\u0627\u0646\u0627\u0626\u06cc \u06a9\u06cc \u0636\u0631\u0648\u0631\u06cc\u0627\u062a \u06a9\u0627 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 90 \u0641\u06cc\u0635\u062f \u062f\u0631\u0622\u0645\u062f \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"story-page-card urdu-story-justify\">\n<div class=\"\">\n<div class=\"story-element story-element-text\">\n<div>\n<p>\u0642\u0627\u0628\u0644 \u0630\u06a9\u0631 \u06c1\u06d2 \u06a9\u06c1 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u06a9\u0645\u06cc \u0627\u06cc\u06a9 \u0628\u0691\u06cc \u0648\u062c\u06c1 \u0628\u0691\u06be\u062a\u06cc \u06c1\u0648\u0626\u06cc \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u0628\u06be\u06cc \u06c1\u06d2\u06d4 \u062c\u0628 \u0644\u0627\u06af\u062a \u0628\u0691\u06be\u062a\u06cc \u06c1\u06d2 \u062a\u0648 \u06a9\u0645\u067e\u0646\u06cc\u0627\u06ba \u0627\u0633 \u06a9\u0627 \u0628\u0648\u062c\u06be \u0635\u0627\u0631\u0641\u06cc\u0646 \u067e\u0631 \u0688\u0627\u0644\u062a\u06cc \u06c1\u06cc\u06ba\u060c \u062c\u0633 \u0633\u06d2 \u06a9\u06be\u0627\u0646\u06d2 \u067e\u06cc\u0646\u06d2 \u06a9\u06cc \u0686\u06cc\u0632\u0648\u06ba \u0633\u06d2 \u0644\u06d2 \u06a9\u0631 \u0627\u0644\u06cc\u06a9\u0679\u0631\u0627\u0646\u06a9 \u0633\u0627\u0645\u0627\u0646 \u062a\u06a9 \u0633\u0628 \u0645\u06c1\u0646\u06af\u0627 \u06c1\u0648 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u06d4 \u0645\u0648\u0688\u06cc\u0632 \u06a9\u06d2 \u062a\u062c\u0632\u06cc\u06d2 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u06af\u0631 \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u0627\u0633\u06cc \u0637\u0631\u062d \u0628\u0631\u0642\u0631\u0627\u0631 \u0631\u06c1\u06cc \u062a\u0648 \u0631\u06cc\u0632\u0631\u0648 \u0628\u06cc\u0646\u06a9 \u0622\u0641 \u0627\u0646\u0688\u06cc\u0627 (\u0622\u0631 \u0628\u06cc \u0622\u0626\u06cc) \u06a9\u0648 \u0633\u0648\u062f \u06a9\u06cc \u0634\u0631\u062d\u0648\u06ba \u0645\u06cc\u06ba \u06a9\u0679\u0648\u062a\u06cc \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u062a\u0627\u062e\u06cc\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 \u0628\u0644\u0646\u062f \u0634\u0631\u062d \u0633\u0648\u062f \u06a9\u0627 \u0645\u0637\u0644\u0628 \u06c1\u06d2 \u06a9\u06c1 \u0645\u06c1\u0646\u06af\u0627 \u0642\u0631\u0636 \u062c\u0633 \u0633\u06d2 \u0644\u0648\u06af \u06a9\u0627\u0631 \u06cc\u0627 \u06af\u06be\u0631 \u062e\u0631\u06cc\u062f\u0646\u06d2 \u062c\u06cc\u0633\u06d2 \u0628\u0691\u06d2 \u0627\u062e\u0631\u0627\u062c\u0627\u062a \u06a9\u0648 \u0645\u0624\u062e\u0631 \u06a9\u0631 \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06af\u06be\u0631\u06cc\u0644\u0648 \u06a9\u06be\u067e\u062a \u0645\u06cc\u06ba \u0622\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u0633\u0633\u062a\u06cc \u0628\u0631\u0627\u06c1 \u0631\u0627\u0633\u062a \u062c\u06cc \u0688\u06cc \u067e\u06cc \u06a9\u06cc \u0631\u0641\u062a\u0627\u0631 \u06a9\u0648 \u06a9\u0645 \u06a9\u0631 \u062f\u06cc\u062a\u06cc \u06c1\u06d2\u06d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div class=\"story-element story-element-text\">\n<div>\n<div>\n<p>Follow us: <a target=\"_blank\" href=\"https:\/\/whatsapp.com\/channel\/0029Va5BRu66hENtZkxJqY0u\">WhatsApp<\/a>,\u00a0<a target=\"_blank\" href=\"https:\/\/www.facebook.com\/qaumiawaz\">Facebook<\/a>, <a target=\"_blank\" href=\"https:\/\/twitter.com\/qaumi_awaz\">Twitter<\/a>, <a target=\"_blank\" href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMO6-_wow6ob5Ag\">Google News<\/a><\/p>\n<p>\u0642\u0648\u0645\u06cc \u0622\u0648\u0627\u0632 \u0627\u0628 \u0679\u06cc\u0644\u06cc \u06af\u0631\u0627\u0645 \u067e\u0631 \u0628\u06be\u06cc \u062f\u0633\u062a\u06cc\u0627\u0628 \u06c1\u06d2\u06d4 \u06c1\u0645\u0627\u0631\u06d2 \u0686\u06cc\u0646\u0644 (<a target=\"_blank\" href=\"https:\/\/t.me\/qaumiawaz\" rel=\"nofollow\">qaumiawaz@<\/a>) \u06a9\u0648 \u062c\u0648\u0627\u0626\u0646 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u06cc\u06c1\u0627\u06ba \u06a9\u0644\u06a9 \u06a9\u0631\u06cc\u06ba \u0627\u0648\u0631 \u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u0648\u06ba \u0633\u06d2 \u0627\u067e \u0688\u06cc\u0679 \u0631\u06c1\u06cc\u06ba\u06d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><center\/><br \/><span\/><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0645\u0646\u0638\u0631 \u0646\u0627\u0645\u06c1 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u0631\u06cc\u06a9\u06c1-\u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0646\u0627\u0632\u06a9 \u06c1\u06d2\u06d4 \u06c1\u0645 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u062a\u06a9 \u06a9\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 i \u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632 \u0646\u06d2 2026 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 \u06a9\u0627 \u062a\u062e\u0645\u06cc\u0646\u06c1 \u0645\u0646\u06af\u0644&#8230;<\/p>\n","protected":false},"author":1,"featured_media":121479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-121478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-india"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/121478\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -\" \/>\n<meta property=\"og:description\" content=\"\u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0645\u0646\u0638\u0631 \u0646\u0627\u0645\u06c1 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u0631\u06cc\u06a9\u06c1-\u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0646\u0627\u0632\u06a9 \u06c1\u06d2\u06d4 \u06c1\u0645 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u062a\u06a9 \u06a9\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 i \u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632 \u0646\u06d2 2026 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 \u06a9\u0627 \u062a\u062e\u0645\u06cc\u0646\u06c1 \u0645\u0646\u06af\u0644...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/121478\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T11:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cf-images.assettype.com\/qaumiawaz%2F2023-06%2Fdf0ff498-90ae-43b5-8b86-815c17fd631b%2FMoodys_IA.jpg?rect=0%2C0%2C1500%2C844&amp;auto=format%2Ccompress&amp;fmt=webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc\",\"datePublished\":\"2026-05-12T11:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg\",\"articleSection\":[\"\u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/121478#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/121478\",\"name\":\"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg\",\"datePublished\":\"2026-05-12T11:03:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/121478\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/121478#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/121478","og_locale":"en_US","og_type":"article","og_title":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -","og_description":"\u0627\u06cc\u062c\u0646\u0633\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0645\u0646\u0638\u0631 \u0646\u0627\u0645\u06c1 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u0631\u06cc\u06a9\u06c1-\u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0646\u0627\u0632\u06a9 \u06c1\u06d2\u06d4 \u06c1\u0645 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0634\u0631\u062d \u0646\u0645\u0648 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 0.8 \u0641\u06cc\u0635\u062f \u067e\u0648\u0627\u0626\u0646\u0679 \u062a\u06a9 \u06a9\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 i \u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632 \u0646\u06d2 2026 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 \u06a9\u0627 \u062a\u062e\u0645\u06cc\u0646\u06c1 \u0645\u0646\u06af\u0644...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/121478","article_published_time":"2026-05-12T11:03:28+00:00","og_image":[{"url":"https:\/\/cf-images.assettype.com\/qaumiawaz%2F2023-06%2Fdf0ff498-90ae-43b5-8b86-815c17fd631b%2FMoodys_IA.jpg?rect=0%2C0%2C1500%2C844&amp;auto=format%2Ccompress&amp;fmt=webp","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc","datePublished":"2026-05-12T11:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg","articleSection":["\u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/121478#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/121478","url":"https:\/\/safirnews.in\/urdu\/archives\/121478","name":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg","datePublished":"2026-05-12T11:03:28+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/121478"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/05\/qaumiawaz2F2023-062Fdf0ff498-90ae-43b5-8b86-815c17fd631b2FMoodys_IA.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/121478#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u2019\u0645\u0648\u0688\u06cc\u0632 \u0631\u06cc\u0679\u0646\u06af\u0632\u2018 \u0646\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u0631\u062d \u0646\u0645\u0648 0.8 \u067e\u0648\u0627\u0626\u0646\u0679\u0633 \u06a9\u0645 \u06a9\u0631 \u06a9\u06d2 6 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u062f\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/121478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=121478"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/121478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/121479"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=121478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=121478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=121478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}