{"id":113335,"date":"2026-02-22T02:20:39","date_gmt":"2026-02-22T02:20:39","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/113335"},"modified":"2026-02-22T02:20:39","modified_gmt":"2026-02-22T02:20:39","slug":"%d8%b9%d8%af%d8%a7%d9%84%d8%aa%db%8c-%d9%81%db%8c%d8%b5%d9%84%db%92-%da%a9%db%92-%d8%a8%d8%b9%d8%af-%d9%b9%d8%b1%d9%85%d9%be-%d9%86%db%92-%d8%b9%d8%a7%d9%84%d9%85%db%8c-%d9%b9%db%8c%d8%b1%d9%81-%da%a9","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/113335","title":{"rendered":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627"},"content":{"rendered":"<p><\/p>\n<div>\n<div>\n<p>\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u062e\u06cc\u0627\u0644 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06af\u0631 \u0627\u0633 \u0679\u06cc\u0631\u0641 \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u0646\u0627\u0641\u0630 \u06c1\u0648 \u06af\u06cc\u0627 \u062a\u0648 \u0627\u0633 \u0633\u06d2 \u0639\u0627\u0644\u0645\u06cc \u062a\u062c\u0627\u0631\u062a \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 \u0627\u0646 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06cc \u0628\u0631\u0622\u0645\u062f\u0627\u062a \u067e\u0631 \u062f\u0628\u0627\u0624 \u0688\u0627\u0644\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u0645\u0631\u06cc\u06a9\u06c1 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u062a\u062c\u0627\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062c\u0648\u0627\u0628\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0628\u06be\u06cc \u0628\u0691\u06be \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0645\u0645\u06a9\u0646\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u062a\u062c\u0627\u0631\u062a\u06cc \u062a\u0646\u0627\u0624 \u06a9\u0648 \u0645\u0632\u06cc\u062f \u062a\u06cc\u0632 \u06a9\u0631 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u06d4\u0641\u06cc \u0627\u0644\u062d\u0627\u0644 \u0679\u0631\u0645\u067e \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u0646\u06d2 \u062a\u0641\u0635\u06cc\u0644\u06cc \u0641\u06c1\u0631\u0633\u062a \u0627\u0648\u0631 \u0679\u0627\u0626\u0645 \u0644\u0627\u0626\u0646 \u062c\u0627\u0631\u06cc \u06a9\u0631\u0646\u0627 \u06c1\u06d2\u06d4<\/p>\n<\/div>\n<\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u062e\u06cc\u0627\u0644 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06af\u0631 \u0627\u0633 \u0679\u06cc\u0631\u0641 \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u0646\u0627\u0641\u0630 \u06c1\u0648 \u06af\u06cc\u0627 \u062a\u0648 \u0627\u0633 \u0633\u06d2 \u0639\u0627\u0644\u0645\u06cc \u062a\u062c\u0627\u0631\u062a \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 \u0627\u0646 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06cc \u0628\u0631\u0622\u0645\u062f\u0627\u062a \u067e\u0631 \u062f\u0628\u0627\u0624 \u0688\u0627\u0644\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u0645\u0631\u06cc\u06a9\u06c1 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u062a\u062c\u0627\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062c\u0648\u0627\u0628\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0628\u06be\u06cc \u0628\u0691\u06be \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0645\u0645\u06a9\u0646\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u062a\u062c\u0627\u0631\u062a\u06cc \u062a\u0646\u0627\u0624&#8230;<\/p>\n","protected":false},"author":1,"featured_media":113336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-113335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/113335\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u062e\u06cc\u0627\u0644 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06af\u0631 \u0627\u0633 \u0679\u06cc\u0631\u0641 \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u0646\u0627\u0641\u0630 \u06c1\u0648 \u06af\u06cc\u0627 \u062a\u0648 \u0627\u0633 \u0633\u06d2 \u0639\u0627\u0644\u0645\u06cc \u062a\u062c\u0627\u0631\u062a \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 \u0627\u0646 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06cc \u0628\u0631\u0622\u0645\u062f\u0627\u062a \u067e\u0631 \u062f\u0628\u0627\u0624 \u0688\u0627\u0644\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u0645\u0631\u06cc\u06a9\u06c1 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u062a\u062c\u0627\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062c\u0648\u0627\u0628\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0628\u06be\u06cc \u0628\u0691\u06be \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0645\u0645\u06a9\u0646\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u062a\u062c\u0627\u0631\u062a\u06cc \u062a\u0646\u0627\u0624...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/113335\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T02:20:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1313\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627\",\"datePublished\":\"2026-02-22T02:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg\",\"articleSection\":[\"\u0639\u0627\u0644\u0645\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/113335#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/113335\",\"name\":\"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg\",\"datePublished\":\"2026-02-22T02:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/113335\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113335#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/113335","og_locale":"en_US","og_type":"article","og_title":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -","og_description":"\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u062e\u06cc\u0627\u0644 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06af\u0631 \u0627\u0633 \u0679\u06cc\u0631\u0641 \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u0646\u0627\u0641\u0630 \u06c1\u0648 \u06af\u06cc\u0627 \u062a\u0648 \u0627\u0633 \u0633\u06d2 \u0639\u0627\u0644\u0645\u06cc \u062a\u062c\u0627\u0631\u062a \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 \u0627\u0646 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06cc \u0628\u0631\u0622\u0645\u062f\u0627\u062a \u067e\u0631 \u062f\u0628\u0627\u0624 \u0688\u0627\u0644\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u0645\u0631\u06cc\u06a9\u06c1 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u062a\u062c\u0627\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062c\u0648\u0627\u0628\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0628\u06be\u06cc \u0628\u0691\u06be \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0645\u0645\u06a9\u0646\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u062a\u062c\u0627\u0631\u062a\u06cc \u062a\u0646\u0627\u0624...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/113335","article_published_time":"2026-02-22T02:20:39+00:00","og_image":[{"width":1313,"height":560,"url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627","datePublished":"2026-02-22T02:20:39+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg","articleSection":["\u0639\u0627\u0644\u0645\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/113335#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/113335","url":"https:\/\/safirnews.in\/urdu\/archives\/113335","name":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg","datePublished":"2026-02-22T02:20:39+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/113335"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/qaumiawaz2F2026-02-222Fta39dpr12FTrump-FFF.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/113335#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u0639\u062f\u0627\u0644\u062a\u06cc \u0641\u06cc\u0635\u0644\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0679\u0631\u0645\u067e \u0646\u06d2 \u0639\u0627\u0644\u0645\u06cc \u0679\u06cc\u0631\u0641 \u06a9\u0648 \u062f\u0633 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0628\u0691\u06be\u0627 \u06a9\u0631 \u067e\u0646\u062f\u0631\u06c1 \u0641\u06cc\u0635\u062f \u06a9\u0631 \u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/113335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=113335"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/113335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/113336"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=113335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=113335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=113335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}