{"id":113313,"date":"2026-02-21T19:32:17","date_gmt":"2026-02-21T19:32:17","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/113313"},"modified":"2026-02-21T19:32:17","modified_gmt":"2026-02-21T19:32:17","slug":"%d9%be%d8%b1%d9%88%d9%81%db%8c%d8%b3%d8%b1-%d9%85%d8%b3%d8%b9%d9%88%d8%af-%d8%a7%d8%ad%d9%85%d8%af-%da%a9%db%8c-%d8%b4%d8%a7%d8%b9%d8%b1%db%8c-%d8%b9%d8%a7%d9%85-%d8%b1%d9%88%d8%a7%db%8c%d8%aa-%d8%b3","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/113313","title":{"rendered":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0"},"content":{"rendered":"<p><\/p>\n<div>\n<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f 20 \u0641\u0631\u0648\u0631\u06cc (\u0627\u0631\u062f\u0648 \u0644\u06cc\u06a9\u0633) \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0631\u0648\u0627\u06cc\u062a\u06cc \u0634\u0627\u0639\u0631\u06cc \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u06c1\u06d2 \u062c\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0645\u06cc\u0646\u062c\u0645\u0646\u0679\u060c \u062a\u062f\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0637\u0628 \u0633\u06d2 \u062a\u0639\u0644\u0642 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u062a\u06cc\u0646\u0648\u06ba \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u0646 \u06a9\u0627 \u0627\u0631\u062f\u0648 \u0627\u062f\u0628 \u0633\u06d2 \u0644\u06af\u0627\u0624 \u0642\u0627\u0628\u0644 \u0633\u062a\u0627\u0626\u0634 \u0627\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u062d\u0633\u06cc\u0646 \u06c1\u06d2<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0646 \u062e\u06cc\u0627\u0644\u0627\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0627\u06cc\u0633 \u0627\u06d2 \u0634\u06a9\u0648\u0631 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u062f\u0627\u0626\u0631\u06c3 \u0627\u0644\u0645\u0639\u0627\u0631\u0641 \u0639\u062b\u0645\u0627\u0646\u06cc\u06c1 \u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u0646\u06d2 \u0633\u0627\u0644\u0627\u0631 \u062c\u0646\u06af \u0645\u06cc\u0648\u0632\u06cc\u0645 \u06a9\u06d2 \u0622\u0688\u06cc\u0679\u0648\u0631\u06cc\u0645 \u0645\u06cc\u06ba \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u06a9\u062a\u0627\u0628\u201d \u0631\u0634\u062d\u0627\u062a \u0645\u0633\u0639\u0648\u062f\u201d \u06a9\u06cc \u0631\u0633\u0645 \u0627\u062c\u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062a\u0642\u0631\u06cc\u0628 \u0633\u06d2 \u062e\u0637\u0627\u0628 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06cc\u0627 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2 \u0627\u0628 \u062a\u06a9 9 \u06a9\u062a\u0627\u0628\u06cc\u06ba \u0634\u0627\u0626\u0639 \u06a9\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0633\u0628 \u0633\u06d2 \u0628\u0691\u06cc \u062e\u0627\u0635 \u0628\u0627\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0648 \u0644\u0648\u06af \u0627\u067e\u0646\u06cc \u062a\u062e\u0644\u06cc\u0642\u0627\u062a \u0645\u0646\u0638\u0631 \u0639\u0627\u0645 \u067e\u0631 \u0644\u0627\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0633 \u0645\u06cc\u06ba \u0627\u0631\u062f\u0648 \u0627\u06a9\u06cc\u0688\u0645\u06cc \u06a9\u0627 \u062c\u0632\u0648\u06cc \u0645\u0627\u0644\u06cc \u062a\u0639\u0627\u0648\u0646 \u0634\u0627\u0645\u0644 \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2 \u062c\u0632\u0648\u06cc \u0627\u0639\u0627\u0646\u062a \u0642\u0628\u0648\u0644 \u06a9\u06cc\u06d2 \u0628\u063a\u06cc\u0631 \u06c1\u06cc \u06cc\u06c1 \u06a9\u0627\u0645 \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u0627 \u06c1\u06d2 \u06cc\u06c1 \u0627\u0646 \u06a9\u06cc \u0627\u0631\u062f\u0648 \u0633\u06d2 \u0633\u0686\u06cc \u0645\u062d\u0628\u062a \u0648 \u0639\u0642\u06cc\u062f\u062a \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u06c1\u06d2<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0645\u062c\u06be\u06d2 \u0645\u0639\u0644\u0648\u0645 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0627\u0631\u062f\u0648 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0641\u0627\u0631\u0633\u06cc \u0633\u06d2 \u0628\u06be\u06cc \u0628\u0691\u06cc \u062f\u0644\u0686\u0633\u067e\u06cc \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0646 \u06a9\u06cc \u0641\u0627\u0631\u0633\u06cc \u0645\u06cc\u06ba \u0628\u06be\u06cc \u062a\u0635\u0646\u06cc\u0641 \u0622\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0633 \u0645\u062d\u0641\u0644 \u0645\u06cc\u06ba \u0634\u0639\u0631\u0627\u0621 \u06a9\u06cc \u0628\u0691\u06cc \u062a\u0639\u062f\u0627\u062f \u06a9\u06cc \u0634\u0631\u06a9\u062a \u067e\u0631 \u0627\u0638\u06c1\u0627\u0631 \u0645\u0633\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u062e\u06cc\u0627\u0644 \u0634\u0639\u0631\u0627 \u06a9\u0627 \u0627\u06cc\u06a9 \u062c\u06af\u06c1 \u062c\u0645\u0639 \u06c1\u0648\u0646\u0627 \u0628\u06c1\u062a \u0628\u0691\u06cc \u0628\u0627\u062a \u06c1\u06d2 \u0627\u0648\u0631 \u06cc\u06c1 \u06a9\u0627\u0645 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2\u0628\u062d\u0633\u0646 \u0628\u062e\u0648\u0628\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u0627 \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0634\u0645\u0627\u0644\u06cc \u06c1\u0646\u062f \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0627\u0631\u062f\u0648 \u06a9\u0627 \u0645\u0631\u06a9\u0632 \u062a\u06be\u0627 \u0627\u0628 \u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f \u06a9\u0648 \u06cc\u06c1 \u0641\u062e\u0631 \u062d\u0627\u0635\u0644 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0628 \u06cc\u06c1 \u0627\u0631\u062f\u0648 \u06a9\u0627 \u0645\u0631\u06a9\u0632 \u0628\u0646 \u06af\u06cc\u0627 \u06c1\u06d2 \u0627\u0631\u062f\u0648 \u0632\u0628\u0627\u0646 \u06a9\u0627 \u062a\u062d\u0641\u0638 \u0627\u06c1\u0644 \u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u06cc\u06c1 \u0628\u0691\u06cc \u062e\u0648\u0634\u06cc \u06a9\u06cc \u0628\u0627\u062a \u0628\u06be\u06cc \u06c1\u06d2 \u06a9\u06c1 \u062a\u0644\u0646\u06af\u0627\u0646\u06c1 \u06a9\u06d2 \u0633\u0631\u06a9\u0627\u0631\u06cc \u0627\u0631\u062f\u0648 \u0645\u06cc\u0688\u06cc\u0645 \u0645\u062f\u0627\u0631\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u0633\u06d2 \u0632\u0627\u0626\u062f \u0637\u0644\u0628\u06c1 \u0648 \u0637\u0627\u0644\u0628\u0627\u062a \u0627\u0631\u062f\u0648 \u0645\u06cc\u0688\u06cc\u0645 \u0645\u06cc\u06ba \u062a\u0639\u0644\u06cc\u0645 \u062d\u0627\u0635\u0644 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0627\u06cc\u0633 \u0627\u06d2 \u0634\u06a9\u0648\u0631 \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u0648 \u0627\u0646 \u06a9\u06cc \u06a9\u062a\u0627\u0628 &#8220;\u0631\u0634\u062d\u0627\u062a \u0645\u0633\u0639\u0648\u062f\u201d \u06a9\u06cc \u0627\u0634\u0627\u0639\u062a \u067e\u0631 \u062f\u0644\u06cc \u0645\u0628\u0627\u0631\u06a9\u0628\u0627\u062f \u062f\u06cc<\/p>\n<p>\u00a0<\/p>\n<p>\u0633\u0627\u0628\u0642 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u062c\u0646\u0631\u0644 \u067e\u0648\u0644\u06cc\u0633 \u0622\u0646\u062f\u06be\u0631\u0627 \u067e\u0631\u062f\u06cc\u0634 \u0648 \u062a\u0644\u0646\u06af\u0627\u0646\u06c1 \u062c\u0646\u0627\u0628 \u0627\u0646\u0648\u0627\u0631 \u0627\u0644\u06c1\u062f\u06cc \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u06a9\u0648 \u0627\u0646 \u06a9\u06cc \u06a9\u062a\u0627\u0628 \u067e\u0631 \u0645\u0628\u0627\u0631\u06a9\u0628\u0627\u062f \u062f\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f \u0645\u06cc\u06ba \u062f\u06a9\u0646\u06cc \u0627\u0631\u062f\u0648 \u06a9\u0627 \u0628\u0648\u0644 \u0628\u0627\u0644\u0627 \u06c1\u06d2 \u062f\u06a9\u0646\u06cc \u0627\u0631\u062f\u0648 \u0645\u06cc\u06ba \u0645\u0631\u0627\u0679\u06be\u06cc\u060c \u062a\u0644\u06af\u0648 \u0627\u0648\u0631 \u06a9\u0646\u0691\u0627 \u06a9\u06cc \u0622\u0645\u06cc\u0632\u0634 \u06c1\u06d2 \u062c\u0646\u0627\u0628 \u0627\u0646\u0648\u0627\u0631 \u0627\u0644\u06be\u062f\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0631\u062f\u0648 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u0627\u062d\u0648\u0644 \u0628\u06c1\u062a \u0633\u0627\u0632\u06af\u0627\u0631 \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0644\u06cc\u06a9\u0646 \u0627\u0641\u0633\u0648\u0633 \u0627\u0633 \u0628\u0627\u062a \u06a9\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0631\u062f\u0648 \u067e\u0691\u06be\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u06a9\u06cc \u062a\u0639\u062f\u0627\u062f \u06a9\u0645 \u06c1\u0648\u062a\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2 \u0633\u0648\u0634\u06cc\u0644 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u06d2 \u0633\u0628\u0628 \u0644\u0648\u06af \u0627\u0631\u062f\u0648 \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u0627\u0648\u0631 \u0627\u0631\u062f\u0648 \u0631\u0633\u0627\u0626\u0644 \u0633\u06d2 \u062f\u0648\u0631 \u06c1\u0648\u062a\u06d2 \u062c\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u06cc\u0633\u06d2 \u06a9\u0679\u06be\u0646 \u0627\u0648\u0631 \u067e\u0631\u0622\u0634\u0648\u0628 \u062d\u0627\u0644\u0627\u062a \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0646\u0648\u06cc\u06ba \u06a9\u062a\u0627\u0628 \u0634\u0627\u0626\u0639 \u06a9\u06cc \u06c1\u06d2<\/p>\n<p>\u00a0<\/p>\n<p>\u062c\u0648 \u0642\u0627\u0628\u0644 \u0645\u0628\u0627\u0631\u06a9 \u0628\u0627\u062f \u06c1\u06cc\u06ba \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0627\u0631\u062f\u0648 \u06a9\u0627 \u067e\u0631\u0686\u0645 \u0644\u06c1\u0631\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u0631\u062f\u0648 \u06a9\u0627 \u0686\u0631\u0627\u063a \u062c\u0644\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0631\u062f\u0648 \u0632\u0628\u0627\u0646 \u0633\u06d2 \u062a\u0639\u0644\u06cc\u0645 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u0627\u0648\u0631 \u0645\u0633\u0627\u0628\u0642\u062a\u06cc \u0627\u0645\u062a\u062d\u0627\u0646\u0627\u062a \u0645\u06cc\u06ba \u0627\u0631\u062f\u0648 \u0632\u0628\u0627\u0646 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0631\u0646\u06d2 \u067e\u0631 \u0632\u0648\u0631 \u062f\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06a9\u0627\u0631\u067e\u0648\u0631\u06cc\u0679 \u0633\u06cc\u06a9\u0679\u0631 \u0645\u06cc\u06ba \u0622\u062c \u0628\u06be\u06cc \u0627\u0631\u062f\u0648 \u0648\u0627\u0644\u0648\u06ba \u06a9\u06cc \u0633\u062e\u062a \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u06a9\u0627\u0631\u067e\u0648\u0631\u06cc\u0679 \u0633\u06cc\u06a9\u0679\u0631 \u0645\u06cc\u06ba \u0645\u062e\u0644\u0648\u0639\u06c1 \u062c\u0627\u0626\u06cc\u062f\u0627\u062f\u0648\u06ba \u06a9\u0627 \u0639\u0644\u0645 \u0646\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0633\u0628\u0628 \u0644\u0648\u06af \u06a9\u0627\u0631\u067e\u0648\u0631\u06cc\u0679 \u0633\u06cc\u06a9\u0679\u0631 \u06a9\u0627 \u0631\u062e \u0646\u06c1\u06cc\u06ba \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u062c\u0627\u0646\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u06a9\u0648 \u0645\u0634\u0648\u0631\u06c1 \u062f\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 \u06a9\u0627\u0631\u067e\u0648\u0631\u06cc\u0679 \u0633\u06cc\u06a9\u0679\u0631 \u06a9\u06d2 \u06a9\u0646 \u0634\u0639\u0628\u0648\u06ba \u0645\u06cc\u06ba \u0627\u0631\u062f\u0648 \u0648\u0627\u0644\u0648\u06ba \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u0627\u0633 \u06a9\u06cc \u0636\u0631\u0648\u0631 \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc \u06a9\u0631\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06cc\u06c1 \u0628\u06be\u06cc \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0631\u062f\u0648 \u06a9\u06d2 \u0641\u0631\u0648\u063a \u06a9\u06d2 \u0644\u06cc\u06d2 \u0632\u0628\u0627\u0646 \u06a9\u0648 \u0645\u0639\u0627\u0634\u0631\u06d2 \u0633\u06d2 \u062c\u0648\u0691\u0646\u0627 \u0628\u06d2 \u062d\u062f \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2 \u0635\u062f\u0631 \u0646\u0634\u06cc\u0646 \u0645\u0627\u0626\u0646\u0627\u0631\u06cc\u0679\u06cc \u06a9\u0645\u06cc\u0634\u0646 \u062a\u0644\u0646\u06af\u0627\u0646\u06c1 \u062c\u0646\u0627\u0628 \u0637\u0627\u0631\u0642 \u0627\u0646\u0635\u0627\u0631\u06cc \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u06a9\u0648 \u062f\u0644\u06cc \u0645\u0628\u0627\u0631\u06a9\u0628\u0627\u062f \u062f\u06cc \u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1<\/p>\n<p>\u00a0<\/p>\n<p>\u06cc\u06c1 \u0645\u062d\u0641\u0644 \u0627\u06cc\u06a9 \u0631\u0633\u0645\u06cc \u0645\u062d\u0641\u0644 \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0633\u062e\u0646 \u0646\u0648\u0627\u0632\u06cc \u06a9\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u06a9\u06cc \u0627\u062f\u0628\u06cc \u0645\u062d\u0646\u062a\u0648\u06ba \u060c\u0641\u06a9\u0631 \u0648 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0648 \u0628\u0635\u062f \u062e\u0644\u0648\u0635 \u0633\u0644\u0627\u0645 \u067e\u06cc\u0634 \u06a9\u06cc\u0627 \u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u06c1\u0648\u0646\u0627 \u060c\u0637\u0628 \u06a9\u06cc \u062e\u062f\u0645\u0627\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u0646\u0627 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0634\u0627\u0639\u0631 \u0648 \u0627\u062f\u06cc\u0628 \u0628\u06be\u06cc \u06c1\u0648\u0646\u0627 \u06cc\u06c1 \u0628\u06c1\u062a \u0628\u0691\u06d2 \u06a9\u0645\u0627\u0644 \u06a9\u06cc \u0628\u0627\u062a \u06c1\u06d2 \u062c\u0646\u0627\u0628 \u0637\u0627\u0631\u0642 \u0627\u0646\u0635\u0627\u0631\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0645\u06cc\u06ba \u06af\u06c1\u0631\u06d2 \u0645\u0639\u0646\u06cc \u067e\u0648\u0634\u06cc\u062f\u06c1 \u06c1\u06cc\u06ba \u0627\u0646 \u06a9\u06d2 \u062e\u06cc\u0627\u0644\u0627\u062a \u062f\u0644 \u06a9\u0648 \u0686\u06be\u0648 \u0644\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0646\u06d2 \u062a\u0645\u0627\u0645 \u0645\u0642\u0631\u0631\u06cc\u0646 \u0633\u06d2 \u06a9\u062a\u0627\u0628 \u06a9\u06cc \u0633\u062a\u0627\u0626\u0634 \u067e\u0631 \u062f\u0644\u06cc \u0627\u0638\u06c1\u0627\u0631 \u062a\u0634\u06a9\u0631 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 8 \u0633\u0627\u0644 \u0645\u06cc\u06ba 9 \u06a9\u062a\u0627\u0628\u06cc\u06ba \u0634\u0627\u0626\u0639 \u06a9\u06cc \u06c1\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0646\u06a9\u0634\u0627\u0641 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0645\u062c\u06be\u06d2 \u0641\u0627\u0631\u0633\u06cc \u0633\u06d2 \u0628\u06be\u06cc \u06af\u06c1\u0631\u06cc \u062f\u0644\u0686\u0633\u067e\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0646\u06d2 \u0627\u0633 \u0627\u062f\u0628\u06cc \u0627\u062c\u0644\u0627\u0633 \u0627\u0648\u0631 \u0645\u0634\u0627\u0639\u0631\u06d2 \u0645\u06cc\u06ba \u0634\u0631\u06a9\u062a \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u062a\u0645\u0627\u0645 \u0645\u0639\u0632\u0632\u06cc\u0646 \u0633\u06d2 \u0627\u0638\u06c1\u0627\u0631 \u062a\u0634\u06a9\u0631 \u0628\u06be\u06cc \u06a9\u06cc\u0627<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0648\u06c1 \u0633\u06cc\u06a9\u06be\u0646\u06d2 \u06a9\u06d2 \u0639\u0645\u0644 \u067e\u0631 \u06c1\u0645\u06cc\u0634\u06c1 \u06cc\u0642\u06cc\u0646 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0633\u06cc\u06a9\u06be\u0646\u0627 \u0627\u0633\u06cc \u0648\u0642\u062a \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u062c\u0628 \u0627\u0633 \u06a9\u06cc \u0633\u0686\u06cc \u062a\u0691\u067e \u06c1\u0648 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 36 \u0633\u0627\u0644 \u0633\u06d2 \u062a\u062f\u0631\u06cc\u0633\u06cc \u062e\u062f\u0645\u0627\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u06d2 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba \u062c\u0633 \u0645\u06cc\u06ba 15 \u0633\u0627\u0644 \u0627\u0646\u062c\u06cc\u0646\u0626\u0631\u0646\u06af \u06a9\u06d2 \u0637\u0644\u0628\u0627\u0621 \u06a9\u0648 \u0627\u0648\u0631 17 \u0633\u0627\u0644 \u0645\u06cc\u0688\u06cc\u06a9\u0644 \u0633\u0627\u0626\u0646\u0633 \u06a9\u06d2 \u0637\u0644\u0628\u06c1 \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645 \u0628\u06be\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06cc\u06c1 \u06a9\u062a\u0627\u0628 \u062a\u0642\u0631\u06cc\u0628\u0627 20 \u0633\u06d2 \u0632\u0627\u0626\u062f \u0628\u062d\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u06a9\u06be\u06cc \u06af\u0626\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0646\u06d2 \u0627\u0633 \u0645\u0648\u0642\u0639 \u067e\u0631 \u0627\u067e\u0646\u06d2 \u067e\u0633\u0646\u062f\u06cc\u062f\u06c1 \u0627\u0634\u0639\u0627\u0631<\/p>\n<p>\u06c1\u06d2 \u0645\u06cc\u0631\u06cc \u062f\u0639\u0627 \u06cc\u06c1 \u062e\u0627\u0644\u0642 \u0633\u06d2 \u0635\u062d\u062a \u0628\u06be\u06cc \u0639\u0637\u0627 \u06a9\u0631 \u062d\u06a9\u0645\u062a \u0628\u06be\u06cc<\/p>\n<p>\u06a9\u0631\u067e\u0627\u0624\u06ba \u0645\u06cc\u06ba \u062e\u062f\u0645\u062a \u062f\u0646\u06cc\u0627 \u06a9\u06cc \u0627\u0648\u0631 \u06a9\u0627\u0645 \u06a9\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0645\u0644\u062a \u06a9\u0627<\/p>\n<p>\u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1<\/p>\n<p>\u0627\u067e\u0646\u0627 \u06a9\u0631\u062f\u0627\u0631 \u06a9\u06be\u0648 \u0646\u06c1\u06cc\u06ba \u0633\u06a9\u062a\u0627<\/p>\n<p>\u06cc\u06c1 \u06a9\u0628\u06be\u06cc \u0645\u062c\u06be \u0633\u06d2 \u06c1\u0648 \u0646\u06c1\u06cc\u06ba \u0633\u06a9\u062a\u0627<\/p>\n<p>\u0633\u0646\u0627\u0626\u06d2 \u062c\u0633\u06d2 \u0633\u0627\u0645\u0639\u06cc\u0646 \u0646\u06d2 \u0628\u06d2 \u062d\u062f \u067e\u0633\u0646\u062f \u06a9\u06cc\u0627\u062c\u0646\u0627\u0628 \u0633\u0631\u0627\u062c \u0627\u0646\u0635\u0627\u0631\u06cc \u0628\u0627\u0646\u06cc \u0627\u0648\u0631 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u0642\u0637\u0631 \u067e\u0631\u06cc\u0645\u06cc\u0626\u0631 \u0644\u06cc\u06af \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0627\u0631\u062f\u0648 \u062e\u062f\u0645\u0627\u062a \u06a9\u06cc \u0632\u0628\u0631\u062f\u0633\u062a \u0633\u062a\u0627\u0626\u0634 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0646 \u06a9\u06cc \u06a9\u062a\u0627\u0628 \u06a9\u06cc \u0627\u0634\u0627\u0639\u062a \u067e\u0631 \u0645\u0628\u0627\u0631\u06a9\u0628\u0627\u062f \u062f\u06cc \u0627\u0648\u0631 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a\u0648\u06ba \u06a9\u0627 \u0644\u0648\u06c1\u0627 \u0645\u0646\u0648\u0627\u06cc\u0627 \u06c1\u06d2 \u062e\u0644\u06cc\u062c\u06cc \u0645\u0645\u0627\u0644\u06a9 \u0645\u06cc\u06ba \u0628\u06be\u06cc \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0639\u0627\u0644\u0645\u06cc \u0645\u0634\u0627\u0639\u0631\u0648\u06ba \u06a9\u06cc \u0635\u062f\u0627\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06c1\u0645 \u06a9\u06cc\u0648 \u067e\u06cc \u0627\u06cc\u0644 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0627\u062f\u0628\u06cc \u0645\u062d\u0641\u0644\u06cc\u06ba \u0628\u06be\u06cc \u0633\u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba \u06af\u0632\u0634\u062a\u06c1 \u0633\u0627\u0644 \u06c1\u0645 \u0646\u06d2 \u067e\u06c1\u0644\u0627 \u0639\u0627\u0644\u0645\u06cc \u0645\u0634\u0627\u0639\u0631\u06c1 \u0645\u0646\u0639\u0642\u062f \u06a9\u06cc\u0627 \u062a\u06be\u0627 \u062c\u0633 \u06a9\u06cc \u0635\u062f\u0627\u0631\u062a \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0646\u06d2 \u06a9\u06cc \u062a\u06be\u06cc \u062c\u0646\u0627\u0628 \u0633\u0631\u0627\u062c \u0627\u0646\u0635\u0627\u0631\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u06c1\u0644\u0627 \u0645\u0634\u0627\u0639\u0631\u06c1 \u06a9\u0627\u0641\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0631\u06c1\u0627 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0639\u0644\u0627\u0646 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0639\u0646\u0642\u0631\u06cc\u0628 \u0642\u0637\u0631 \u0645\u06cc\u06ba \u062f\u0648\u0633\u0631\u0627 \u0639\u0627\u0644\u0645\u06cc \u0645\u0634\u0627\u0639\u0631\u06c1 \u0645\u0646\u0639\u0642\u062f \u06c1\u0648\u06af\u0627 \u062c\u0633 \u06a9\u06cc \u0635\u062f\u0627\u062a \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06c1\u06cc \u06a9\u0631\u06cc\u06ba \u06af\u06d2 \u0645\u062e\u062f\u0648\u0645 \u06cc\u0627\u0641\u062a\u06c1 \u0645\u0634\u06c1\u0648\u0631 \u0634\u0627\u0639\u0631 \u0688\u0627\u06a9\u0679\u0631 \u0641\u0627\u0631\u0648\u0642 \u0634\u06a9\u06cc\u0644 \u060c\u0645\u0648\u0644\u0627\u0646\u0627 \u0627\u0628\u0648\u0627\u0644\u06a9\u0644\u0627\u0645 \u0622\u0632\u0627\u062f \u0627\u06cc\u0648\u0627\u0631\u0688 \u06cc\u0627\u0641\u062a\u06c1 \u0645\u0645\u062a\u0627\u0632 \u0648 \u0633\u06cc\u0646\u06cc\u0626\u0631 \u0634\u0627\u0639\u0631 \u0688\u0627\u06a9\u0679\u0631 \u0645\u062d\u0633\u0646 \u062c\u0644\u06af\u0627\u0646\u0648\u06cc \u0627\u0648\u0631 \u062c\u0646\u0627\u0628 \u0627\u0631\u0634\u0627\u062f \u0633\u06c1\u06cc\u0644 \u0639\u0645\u0631\u06cc \u0646\u06d2 \u06a9\u062a\u0627\u0628 \u067e\u0631 \u0627\u0638\u06c1\u0627\u0631 \u062e\u06cc\u0627\u0644 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06cc\u06c1 \u06a9\u062a\u0627\u0628 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0645\u0639\u0644\u0648\u0645\u0627\u062a\u06cc \u06c1\u06d2 \u0627\u0633 \u06a9\u0627 \u06c1\u0631 \u06af\u06be\u0631 \u0645\u06cc\u06ba \u06c1\u0648\u0646\u0627 \u0646\u06c1\u0627\u06cc\u062a \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u06a9\u0648 \u0627\u0631\u062f\u0648 \u0634\u0627\u0639\u0631\u06cc \u06a9\u0627 \u0627\u06cc\u06a9 \u0645\u0639\u062a\u0628\u0631 \u06c1\u06d2 \u0627\u0648\u0631 \u0628\u0627 \u0648\u0642\u0627\u0631 \u0634\u0627\u0639\u0631 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u0627\u0648\u0631 \u0627\u0646 \u06a9\u06cc \u0627\u062f\u0628\u06cc \u062e\u062f\u0645\u0627\u062a \u06a9\u0648 \u062e\u0631\u0627\u062c \u062a\u062d\u0633\u06cc\u0646 \u067e\u06cc\u0634 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0639\u0631\u06cc \u0648\u062a\u0635\u0646\u06cc\u0641\u06cc \u062e\u062f\u0645\u0627\u062a \u0634\u0627\u0639\u0631\u0648\u06ba \u0627\u0648\u0631 \u0627\u062f\u06cc\u0628\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u0634\u0639\u0644 \u0631\u0627\u06c1 \u06c1\u06d2\u0627\u062f\u0628\u06cc \u0645\u062d\u0641\u0644 \u06a9\u06cc \u06a9\u0627\u0631\u0648\u0627\u0626\u06cc \u0688\u0627\u06a9\u0679\u0631 \u0622\u0635\u0641 \u0639\u0644\u06cc \u0646\u06d2 \u0686\u0644\u0627\u0626\u06cc \u0628\u0639\u062f \u0627\u0632\u0627\u06ba \u0645\u062e\u062f\u0648\u0645 \u0627\u06cc\u0648\u0627\u0631\u0688 \u06cc\u0627\u0641\u062a\u06c1 \u0645\u0634\u06c1\u0648\u0631 \u0634\u0627\u0639\u0631 \u0688\u0627\u06a9\u0679\u0631 \u0641\u0627\u0631\u0648\u0642 \u0634\u06a9\u06cc\u0644 \u06a9\u06cc \u0635\u062f\u0627\u0631\u062a \u0645\u06cc\u06ba \u0645\u0634\u0627\u0639\u0631\u06c1 \u0645\u0646\u0639\u0642\u062f \u06c1\u0648\u0627 \u062c\u0646\u0627\u0628 \u0644\u0637\u06cc\u0641 \u0627\u0644\u062f\u06cc\u0646 \u0644\u0637\u06cc\u0641 \u0646\u06d2 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u06a9\u0644\u0645\u0627\u062a \u0627\u062f\u0627 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062c\u0646\u0627\u0628 \u0634\u06a9\u06cc\u0644 \u062d\u06cc\u062f\u0631 \u06a9\u0627\u0646\u067e\u0648\u0631\u06cc \u06a9\u0648 \u0646\u0638\u0627\u0645\u062a \u062d\u0648\u0627\u0644\u06d2 \u06a9\u06cc \u062c\u0646\u0627\u0628 \u0634\u06a9\u06cc\u0644 \u062d\u06cc\u062f\u0631 \u06a9\u0627\u0646\u067e\u0648\u0631\u06cc \u0646\u06d2 \u0628\u0691\u06cc \u06c1\u06cc \u0639\u0645\u062f\u06af\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0646\u0641\u0631\u062f \u0627\u0646\u062f\u0627\u0632 \u0645\u06cc\u06ba \u0645\u0634\u0627\u0639\u0631\u06d2 \u06a9\u06cc \u0646\u0638\u0627\u0645\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc<\/p>\n<p>\u00a0<\/p>\n<p>\u0635\u062f\u0631 \u0645\u0634\u0627\u0639\u0631\u06c1 \u0688\u0627\u06a9\u0679\u0631 \u0641\u0627\u0631\u0648\u0642 \u0634\u06a9\u06cc\u0644 \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 \u060c \u0627\u0641\u0633\u0631 \u062f\u06a9\u0646\u06cc \u0645\u0645\u0628\u0626\u06cc\u060c \u0688\u0627\u06a9\u0679\u0631 \u0633\u062a\u0627\u0631 \u0633\u0627\u062d\u0631 \u0627\u0646\u0646\u062a \u067e\u0648\u0631\u060c \u0633\u06cc\u0646\u06cc\u0626\u0631 \u0634\u0627\u0639\u0631 \u062c\u0646\u0627\u0628 \u0635\u0644\u0627\u062d \u0627\u0644\u062f\u06cc\u0646 \u0646\u06cc\u0631\u060c \u0688\u0627\u06a9\u0679\u0631 \u0645\u062d\u0633\u0646 \u062c\u0644\u06af\u0627\u0646\u0648\u06cc\u060c \u0635\u0648\u0641\u06cc \u0633\u0644\u0637\u0627\u0646 \u0634\u0637\u0627\u0631\u06cc\u060c \u0633\u0631\u062f\u0627\u0631 \u0633\u0644\u06cc\u0645\u060c\u0633\u0645\u06cc\u0639 \u0627\u0644\u0644\u06c1 \u062d\u0633\u06cc\u0646\u06cc \u0633\u0645\u06cc\u0639\u060c \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f\u060c \u0638\u0641\u0631 \u0641\u0627\u0631\u0648\u0642\u06cc \u060c\u0646\u0648\u06cc\u062f \u062c\u0639\u0641\u0631\u06cc \u060c\u0627\u0646\u062c\u0646\u06cc \u06a9\u0645\u0627\u0631 \u06af\u0648\u0626\u0644\u060c \u0627\u0631\u0634\u062f \u0634\u0631\u0641\u06cc\u060c \u0634\u06a9\u06cc\u0644 \u062d\u06cc\u062f\u0631\u060c \u062c\u06c1\u0627\u0646\u06af\u06cc\u0631 \u0642\u06cc\u0627\u0633\u060c \u0633\u0639\u062f \u0627\u0644\u0644\u06c1 \u062e\u0627\u0646 \u0633\u0628\u06cc\u0644\u060c \u062b\u0646\u0627 \u0627\u0644\u0644\u06c1 \u0648\u0635\u0641\u06cc\u060c \u0633\u06c1\u06cc\u0644 \u0639\u0638\u06cc\u0645\u060c \u0633\u06cc\u062f \u0627\u0633\u0645\u0627\u0639\u06cc\u0644 \u0630\u0628\u06cc\u062d \u0627\u0644\u0644\u06c1\u060c \u0639\u0628\u062f\u0627\u0644\u0634\u06a9\u0648\u0631 \u0634\u0627\u062f\u0627\u0628\u060c \u060c\u062d\u0646\u0627\u0621 \u0634\u06c1\u06cc\u062f\u06cc\u060c \u062a\u0642\u06cc\u06cc\u06c1 \u063a\u0632\u0644\u060c \u0627\u0631\u062c\u0645\u0646\u062f \u0628\u0627\u0646\u0648\u060c \u0635\u0628\u06cc\u062d\u06c1 \u062a\u0628\u0633\u0645\u060c \u0622\u0631\u0632\u0648 \u0645\u06c1\u06a9 \u0627\u0648\u0631 \u0631\u0641\u06cc\u0639\u06c1 \u0646\u0648\u0634\u06cc\u0646 \u0646\u06d2 \u06a9\u0644\u0627\u0645 \u0633\u0646\u0627\u06cc\u0627 \u0637\u0646\u0632\u0648 \u0645\u0632\u0627\u062d \u06a9\u06d2 \u0645\u0645\u062a\u0627\u0632 \u0634\u0639\u0631\u0627 \u0688\u0627\u06a9\u0679\u0631 \u0634\u0627\u06c1\u062f \u0639\u062f\u06cc\u0644\u06cc\u060c \u0686\u0686\u0627 \u067e\u0627\u0644\u0645\u0648\u0631\u06cc\u060c\u0648\u062d\u06cc\u062f \u067e\u0627\u0634\u0627\u06c1 \u0642\u0627\u062f\u0631\u06cc\u060c\u0644\u0637\u06cc\u0641 \u0627\u0644\u062f\u06cc\u0646 \u0644\u0637\u06cc\u0641\u060c \u0634\u0628\u06cc\u0631 \u062e\u0627\u0646 \u0627\u0633\u0645\u0627\u0631\u0679 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0645\u0632\u0627\u062d\u06cc\u06c1 \u06a9\u0644\u0627\u0645 \u0633\u06d2 \u0645\u062d\u0641\u0644 \u06a9\u0648 \u0632\u0639\u0641\u0631\u0627\u0646 \u0632\u0627\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u062c\u0646\u0627\u0628 \u0634\u0627\u06c1\u062f \u0639\u062f\u06cc\u0644\u06cc \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f\u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u0648 \u0634\u0627\u0644 \u067e\u06cc\u0634 \u06a9\u06cc<\/p>\n<p>\u00a0<\/p>\n<p>\u0645\u0645\u062a\u0627\u0632 \u06af\u0644\u0648\u06a9\u0627\u0631 \u062c\u0646\u0627\u0628 \u0639\u062f\u0646\u0627\u0646 \u0633\u0627\u0644\u0645 \u0646\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u063a\u0632\u0644 \u0633\u0646\u0627\u0626\u06cc \u062c\u0648 \u0628\u06d2 \u062d\u062f \u067e\u0633\u0646\u062f \u06a9\u06cc \u06af\u0626\u06cc \u0627\u0633 \u0645\u0648\u0642\u0639 \u067e\u0631 \u06a9\u06cc\u0648 \u067e\u06cc \u0627\u06cc\u0644 \u06a9\u06d2 \u0645\u0645\u0628\u0631\u0627\u0646 \u062c\u0646\u0627\u0628 \u0633\u06cc\u0641 \u0627\u0644\u0644\u06c1 \u062c\u0646\u0627\u0628 \u0645\u062d\u0645\u062f \u0633\u0645\u06cc\u0631 \u062c\u0646\u0627\u0628 \u0645\u062d\u0645\u062f \u0639\u0628\u062f\u0627\u0644\u0645\u0642\u062a\u062f\u0631 \u062c\u0646\u0627\u0628 \u0634\u06cc\u062e \u0637\u0644\u062d\u06c1 \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 \u062c\u0646\u0627\u0628 \u0633\u06cc\u062f \u0638\u06c1\u0648\u0631 \u0627\u0644\u062f\u06cc\u0646 \u0635\u062f\u0631 \u0646\u0634\u06cc\u0646 \u0633\u06a9\u0646\u062f\u0631 \u0622\u0628\u0627\u062f \u06a9\u0648\u0622\u067e\u0631\u06cc\u0679\u0648 \u0628\u06cc\u0646\u06a9\u060c \u0645\u0645\u062a\u0627\u0632 \u0633\u06cc\u0646\u06cc\u0626\u0631 \u0635\u062d\u0627\u0641\u06cc \u062c\u0646\u0627\u0628 \u06a9\u06d2\u0627\u06cc\u0646 \u0648\u0627\u0635\u0641\u060c \u0645\u062d\u0645\u062f \u062d\u0633\u0627\u0645 \u0627\u0644\u062f\u06cc\u0646 \u0631\u06cc\u0627\u0636\u060c \u062c\u0646\u0627\u0628 \u0633\u06cc\u062f \u0627\u0635\u063a\u0631 \u062d\u0633\u06cc\u0646\u06cc \u060c\u062c\u0646\u0627\u0628 \u0645\u062d\u0645\u062f \u0635\u0628\u063a\u062a \u0627\u0644\u0644\u06c1 \u0634\u0627\u06c1\u062f \u060c\u0645\u062e\u062a\u0627\u0631 \u0627\u062d\u0645\u062f \u0641\u0631\u062f\u06cc\u0646 \u0627\u0648\u0631 \u062f\u06cc\u06af\u0631 \u0645\u0639\u0632\u0632\u06cc\u0646 \u0628\u06be\u06cc \u0645\u0648\u062c\u0648\u062f \u062a\u06be\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06d2 \u0634\u06a9\u0631\u06cc\u06c1 \u067e\u0631 \u062a\u0642\u0631\u06cc\u0628 \u06a9\u0627 \u0627\u062e\u062a\u062a\u0627\u0645 \u0639\u0645\u0644 \u0645\u06cc\u06ba \u0622\u06cc\u0627<\/p>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f 20 \u0641\u0631\u0648\u0631\u06cc (\u0627\u0631\u062f\u0648 \u0644\u06cc\u06a9\u0633) \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0631\u0648\u0627\u06cc\u062a\u06cc \u0634\u0627\u0639\u0631\u06cc \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u06c1\u06d2 \u062c\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0645\u06cc\u0646\u062c\u0645\u0646\u0679\u060c \u062a\u062f\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0637\u0628 \u0633\u06d2 \u062a\u0639\u0644\u0642 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u062a\u06cc\u0646\u0648\u06ba \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u0646 \u06a9\u0627 \u0627\u0631\u062f\u0648 \u0627\u062f\u0628 \u0633\u06d2 \u0644\u06af\u0627\u0624 \u0642\u0627\u0628\u0644 \u0633\u062a\u0627\u0626\u0634 \u0627\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u062d\u0633\u06cc\u0646 \u06c1\u06d2&#8230;<\/p>\n","protected":false},"author":1,"featured_media":113314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-113313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/113313\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -\" \/>\n<meta property=\"og:description\" content=\"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f 20 \u0641\u0631\u0648\u0631\u06cc (\u0627\u0631\u062f\u0648 \u0644\u06cc\u06a9\u0633) \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0631\u0648\u0627\u06cc\u062a\u06cc \u0634\u0627\u0639\u0631\u06cc \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u06c1\u06d2 \u062c\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0645\u06cc\u0646\u062c\u0645\u0646\u0679\u060c \u062a\u062f\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0637\u0628 \u0633\u06d2 \u062a\u0639\u0644\u0642 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u062a\u06cc\u0646\u0648\u06ba \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u0646 \u06a9\u0627 \u0627\u0631\u062f\u0648 \u0627\u062f\u0628 \u0633\u06d2 \u0644\u06af\u0627\u0624 \u0642\u0627\u0628\u0644 \u0633\u062a\u0627\u0626\u0634 \u0627\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u062d\u0633\u06cc\u0646 \u06c1\u06d2...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/113313\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-21T19:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1313\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0\",\"datePublished\":\"2026-02-21T19:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg\",\"articleSection\":[\"\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/113313#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/113313\",\"name\":\"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg\",\"datePublished\":\"2026-02-21T19:32:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/113313\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg\",\"width\":1477,\"height\":908},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/113313#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/113313","og_locale":"en_US","og_type":"article","og_title":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -","og_description":"\u062d\u06cc\u062f\u0631\u0622\u0628\u0627\u062f 20 \u0641\u0631\u0648\u0631\u06cc (\u0627\u0631\u062f\u0648 \u0644\u06cc\u06a9\u0633) \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u062d\u0645\u062f \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0631\u0648\u0627\u06cc\u062a\u06cc \u0634\u0627\u0639\u0631\u06cc \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u06c1\u06d2 \u062c\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u0645\u06cc\u0646\u062c\u0645\u0646\u0679\u060c \u062a\u062f\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0637\u0628 \u0633\u06d2 \u062a\u0639\u0644\u0642 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u062a\u06cc\u0646\u0648\u06ba \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u0646 \u06a9\u0627 \u0627\u0631\u062f\u0648 \u0627\u062f\u0628 \u0633\u06d2 \u0644\u06af\u0627\u0624 \u0642\u0627\u0628\u0644 \u0633\u062a\u0627\u0626\u0634 \u0627\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u062d\u0633\u06cc\u0646 \u06c1\u06d2...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/113313","article_published_time":"2026-02-21T19:32:17+00:00","og_image":[{"width":1313,"height":560,"url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0","datePublished":"2026-02-21T19:32:17+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg","articleSection":["\u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/113313#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/113313","url":"https:\/\/safirnews.in\/urdu\/archives\/113313","name":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg","datePublished":"2026-02-21T19:32:17+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/113313"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/02\/IMG-20260222-WA0002.jpg","width":1477,"height":908},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/113313#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0645\u0633\u0639\u0648\u062f \u0627\u062d\u0645\u062f \u06a9\u06cc \u0634\u0627\u0639\u0631\u06cc \u0639\u0627\u0645 \u0631\u0648\u0627\u06cc\u062a \u0633\u06d2 \u06c1\u0679 \u06a9\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0634\u0639\u0628\u0648\u06ba \u06a9\u0627 \u0627\u062d\u0627\u0637\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/113313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=113313"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/113313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/113314"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=113313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=113313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=113313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}