{"id":110885,"date":"2026-01-31T18:05:34","date_gmt":"2026-01-31T18:05:34","guid":{"rendered":"https:\/\/safirnews.in\/urdu\/archives\/110885"},"modified":"2026-01-31T18:05:34","modified_gmt":"2026-01-31T18:05:34","slug":"%d8%b3%d9%88%d9%86%db%92-%d8%a7%d9%88%d8%b1-%da%86%d8%a7%d9%86%d8%af%db%8c-%da%a9%db%8c-%d9%82%db%8c%d9%85%d8%aa%db%8c%da%ba-%d8%a2%d8%b3%d9%85%d8%a7%d9%86-%d8%b3%db%92-%d8%b2%d9%85%db%8c%d9%86-2","status":"publish","type":"post","link":"https:\/\/safirnews.in\/urdu\/archives\/110885","title":{"rendered":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631"},"content":{"rendered":"<p><\/p>\n<div>\n<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u06a9\u06d2 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u062c\u06c1\u0627\u06ba \u06af\u0632\u0634\u062a\u06c1 \u0686\u0646\u062f \u062f\u0646\u0648\u06ba \u0633\u06d2 \u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0628\u0631\u062f\u0633\u062a \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba1 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u0645 \u06c1\u0648 \u06af\u0626\u06cc \u062c\u0628 \u06a9\u06c1 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba 33\u060c000 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0646 \u0642\u06cc\u0645\u062a\u06cc \u062f\u06be\u0627\u062a\u0648\u06ba \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0646\u06c1 \u0635\u0631\u0641 \u0641\u06cc\u0648\u0686\u0631 \u0679\u0631\u06cc\u0688\u0646\u06af \u0628\u0644\u06a9\u06c1 \u0645\u0642\u0627\u0645\u06cc \u0645\u0627\u0631\u06a9\u06cc\u0679 \u0645\u06cc\u06ba \u0628\u06be\u06cc \u062a\u06cc\u0632\u06cc \u0633\u06d2 \u06af\u0631\u0627\u0648\u0679 \u062f\u06cc\u06a9\u06be\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4 \u0645\u0627\u06c1\u0631\u06cc\u0646 \u067e\u06c1\u0644\u06d2 \u0633\u06d2 \u06c1\u06cc \u0627\u0646 \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0646\u0645\u0627\u06cc\u0627\u06ba \u06a9\u0645\u06cc \u06a9\u06cc \u067e\u06cc\u0634 \u06af\u0648\u0626\u06cc \u06a9\u0631 \u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u0627\u0648\u0631 \u0627\u06cc\u0633\u0627 \u06c1\u06cc \u06c1\u0648\u0627 \u06c1\u06d2\u06d4\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u06cc \u067e\u06cc\u0634\u06cc\u0646 \u06af\u0648\u0626\u06cc\u0627\u06ba \u062f\u0631\u0633\u062a \u062b\u0627\u0628\u062a \u06c1\u0648\u0626\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0628\u0627\u0644\u0622\u062e\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0686\u0645\u06a9 \u067e\u06be\u06cc\u06a9\u06cc \u067e\u0691\u06af\u0626\u06cc \u06c1\u067e\u06d2\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u062c\u06cc \u06c1\u0627\u06ba \u0627\u06cc\u06a9 \u06a9\u0644\u0648 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0645\u06cc\u06ba \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u062f\u0646 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u06cc \u06a9\u0645\u06cc \u06c1\u0648\u0626\u06cc \u06c1\u06d2\u06d4 \u06af\u0632\u0634\u062a\u06c1 \u062c\u0645\u0639\u0631\u0627\u062a \u06a9\u0648 \u0645\u0644\u0679\u06cc \u06a9\u0645\u0648\u0688\u0679\u06cc \u0627\u06cc\u06a9\u0633\u0686\u06cc\u0646\u062c \u0645\u06cc\u06ba \u0646\u0626\u06cc \u0628\u0644\u0646\u062f\u06cc \u062a\u06a9 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u06cc\u06c1 \u0622\u062e\u0631 \u06a9\u0627\u0631 3,99,893 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc \u06a9\u0644\u0648\u06af\u0631\u0627\u0645 \u067e\u0631 \u0628\u0646\u062f \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0645\u0639\u06c1 \u06a9\u0648 \u0641\u06cc\u0648\u0686\u0631 \u0679\u0631\u06cc\u0688\u0646\u06af \u06a9\u06d2 \u0627\u062e\u062a\u062a\u0627\u0645 \u067e\u06315 \u0645\u0627\u0631\u0686 \u06a9\u06cc \u0627\u06cc\u06a9\u0633\u067e\u0627\u0626\u0631\u06cc \u0688\u06cc\u0679 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u062a\u06cc\u0632\u06cc \u0633\u06d2 \u06af\u0631 \u06a9\u0631 2,91,922 \u0631\u0648\u067e\u0626\u06d2 \u067e\u0631 \u0622\u06af\u0626\u06cc\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0633 \u06a9\u0627 \u0645\u0637\u0644\u0628 \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u06a9 \u06c1\u06cc \u062c\u06be\u0679\u06a9\u06d2 \u0645\u06cc\u06ba \u06cc\u06c1 1,07,971 \u0641\u06cc \u06a9\u0644\u0648 \u0633\u0633\u062a\u06cc \u06c1\u0648\u06af\u0626\u06cc \u06c1\u06d2\u06d4\u0627\u0628\u06be\u06cc \u0627\u06cc\u06a9 \u062f\u0646 \u067e\u06c1\u0644\u06d2 \u06c1\u06cc \u062c\u0645\u0639\u0631\u0627\u062a \u06a9\u0648 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0646\u06d2 \u0631\u0627\u06a9\u0679 \u06a9\u06cc \u0631\u0641\u062a\u0627\u0631 \u0633\u06d2 \u067e\u06c1\u0644\u06cc \u0628\u0627\u06314 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0641\u06cc \u06a9\u0644\u0648 \u06af\u0631\u0627\u0645 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0628\u0644\u0646\u062f \u062a\u0631\u06cc\u0646 \u0633\u0637\u062d \u067e\u0627\u0631 \u06a9\u06cc \u062a\u06be\u06cc \u0627\u0648\u0631 \u06cc\u06c1 4,20,048 \u0631\u0648\u067e\u06d2 \u0641\u06cc \u06a9\u0644\u0648\u06af\u0631\u0627\u0645 \u06a9\u06cc \u0628\u0644\u0646\u062f \u062a\u0631\u06cc\u0646 \u0633\u0637\u062d \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u06cc\u06a9 \u06c1\u06cc \u062c\u06be\u0679\u06a9\u06d2 \u0645\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u067e\u0631\u067e\u06c1\u0646\u0686\u06cc \u0686\u0627\u0646\u062f\u06cc \u0646\u06d2\u0627\u0686\u0627\u0646\u06a9 \u06c1\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u0648 \u062a\u06af\u0691\u0627 \u062c\u06be\u0679\u06a9\u0627 \u062f\u06cc\u0627<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u0648\u0631 \u0627\u0633 \u0627\u0639\u0644\u06cc \u0633\u0637\u062d \u0633\u06d2 128,126 \u0631\u0648\u067e\u0626\u06d2 \u0645\u06cc\u06ba \u0645\u062d\u0636 \u0627\u06cc\u06a9 \u062f\u0646 \u0645\u06cc\u06ba \u0633\u0633\u062a\u06cc \u06c1\u0648\u06af\u0626\u06cc\u06d4\u0627\u0633 \u062f\u0648\u0631\u0627\u0646 \u0646\u06c1 \u0635\u0631\u0641 \u0686\u0627\u0646\u062f\u06cc \u0628\u0644\u06a9\u06c1 \u0633\u0648\u0646\u06d2 \u06a9\u0627 \u0628\u0644\u0628\u0644\u06c1 \u0628\u06be\u06cc \u067e\u06be\u0648\u0679\u062a\u0627 \u0646\u0637\u0631 \u0622\u06cc\u0627\u06d4 10 \u06af\u0631\u0627\u0645 24 \u06a9\u06cc\u0631\u0679 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u06a9\u0627\u0631\u0648\u0628\u0627\u0631\u06cc \u062f\u0646 \u0645\u06cc\u06ba 33,113 \u0631\u0648\u067e\u0626\u06d2 \u062a\u06a9 \u06af\u0631 \u06af\u0626\u06cc \u06c1\u06d2\u06d4 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0628\u0631\u062f\u0633\u062a \u06af\u0631\u0627\u0648\u0679 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0628\u0691\u06cc \u06af\u0631\u0627\u0648\u0679 \u0633\u06d2 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631 \u062d\u06cc\u0631\u0627\u0646 \u0648\u067e\u0631\u06cc\u0634\u0627\u0646 \u06c1\u0648\u06af\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u0627\u06cc\u0645 \u0633\u06cc \u0627\u06cc\u06a9\u0633 \u067e\u0631 2 \u0627\u067e\u0631\u06cc\u0644 \u06a9\u0648 \u062e\u062a\u0645 \u06c1\u0648 \u0631\u06c1\u06cc \u06c1\u06d2 \u0645\u062f\u062a \u0648\u0627\u0644\u0627\u0644\u06d2 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u062c\u0645\u0639\u0631\u0627\u062a \u06a9\u0648 183,962 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u067e\u0631 \u0628\u0646\u062f \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc \u0627\u0648\u0631 \u062c\u0645\u0639\u06c1 \u06a9\u06d2 \u0627\u062e\u062a\u062a\u0627\u0645 \u062a\u06a9 \u06cc\u06c1 150,849 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u067e\u0631 \u0628\u0646\u062f \u06c1\u0648\u0626\u06cc\u06d4\u0627\u06af\u0631 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0627\u0648\u0646\u0686\u06cc \u0633\u0637\u062d \u0633\u06d2 \u0627\u0633 \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0622\u0626\u06cc \u06a9\u0645\u06cc \u067e\u0631 \u063a\u0648\u0631 \u06a9\u0631\u06cc\u06ba \u062a\u0648 \u062c\u0645\u0639\u0631\u0627\u062a \u06a9\u0648 \u06c1\u06cc \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0637\u0631\u062d \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u062a\u06cc\u0632\u06cc \u0633\u06d2 \u0628\u0691\u06be \u06a9\u0631 1,93,096 \u06a9\u06cc \u0644\u0627\u0626\u0641 \u0679\u0627\u0626\u0645 \u06c1\u0627\u0626\u06cc \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc \u062a\u06be\u06cc\u06ba \u0627\u0648\u0631 \u067e\u06be\u0631 \u0627\u0686\u0627\u0646\u06a9 \u0627\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u0633\u06cc \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06a9\u06c1<\/p>\n<p>\u00a0<\/p>\n<p>\u0633\u0648\u0646\u0627 \u0627\u0633 \u0628\u0644\u0646\u062f\u06cc \u0633\u06d2 42,247 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u0646\u06cc\u0686\u06d2 \u0622\u06af\u06cc\u0627\u06d4\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06d2 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0645\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u067e\u06c1\u0644\u06d2 \u06c1\u06cc \u0627\u0633 \u0628\u0644\u0646\u062f\u06cc \u062a\u06a9 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u062a\u06cc\u0632\u06cc \u0633\u06d2 \u06af\u0631\u0627\u0648\u0679 \u06a9\u06cc \u067e\u06cc\u0634 \u06af\u0648\u0626\u06cc \u06a9\u06cc \u062a\u06be\u06cc \u0627\u0648\u0631 \u062c\u0645\u0639\u06c1 \u06a9\u0648 \u0627\u0646 \u06a9\u06cc \u06cc\u06c1 \u067e\u06cc\u0634\u06cc\u0646 \u06af\u0648\u0626\u06cc\u0627\u06ba \u062f\u0631\u0633\u062a \u062b\u0627\u0628\u062a \u06c1\u0648\u0626\u06cc\u06ba\u06d4 \u0627\u06af\u0631 \u06c1\u0645 \u0627\u0646 \u0642\u06cc\u0645\u062a\u06cc \u0627\u0634\u06cc\u0627 \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u06a9\u0645\u06cc \u06a9\u06cc \u0648\u062c\u0648\u06c1\u0627\u062a \u067e\u0631 \u063a\u0648\u0631 \u06a9\u0631\u06cc\u06ba \u062a\u0648 \u0627\u0633 \u06a9\u06cc \u0627\u06cc\u06a9 \u0646\u06c1\u06cc\u06ba \u06a9\u0626\u06cc \u0648\u062c\u0648\u06c1\u0627\u062a \u0646\u0638\u0631 \u0622\u062a\u06cc \u06c1\u06cc\u06ba\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u0633\u0648\u0646\u06d2 \u0686\u0627\u0646\u062f\u06cc \u0645\u06cc\u06ba \u0628\u0691\u06cc \u06af\u0631\u0627\u0648\u0679 \u06a9\u06cc \u0627\u06cc\u06a9 \u0627\u06c1\u0645 \u0648\u062c\u06c1 \u067e\u0631\u0627\u0641\u0679 \u0628\u06a9\u0646\u06af \u062a\u06be\u06cc\u06d4 \u062a\u0627\u0631\u06cc\u062e\u06cc \u0633\u0637\u062d \u067e\u0631 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u0646\u06d2 \u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u0645\u06cc\u06ba \u0645\u0646\u0627\u0641\u0639 \u0628\u06a9 \u06a9\u0631\u0646\u0627 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u0627 \u0627\u0648\u0631 \u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u062f\u0628\u0627\u0624 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u062f\u0648\u0646\u0648\u06ba \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0627\u0686\u0627\u0646\u06a9 \u06af\u0631 \u06af\u0626\u06cc\u06ba\u06d4<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n<p>[]<br \/>\n<br \/><a href=\"[]\"> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u06a9\u06d2 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u062c\u06c1\u0627\u06ba \u06af\u0632\u0634\u062a\u06c1 \u0686\u0646\u062f \u062f\u0646\u0648\u06ba \u0633\u06d2 \u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0628\u0631\u062f\u0633\u062a \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba1 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u0645 \u06c1\u0648 \u06af\u0626\u06cc \u062c\u0628 \u06a9\u06c1 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba 33\u060c000 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u00a0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":110882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-110885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hyderabad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safirnews.in\/urdu\/archives\/110885\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -\" \/>\n<meta property=\"og:description\" content=\"\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u06a9\u06d2 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u062c\u06c1\u0627\u06ba \u06af\u0632\u0634\u062a\u06c1 \u0686\u0646\u062f \u062f\u0646\u0648\u06ba \u0633\u06d2 \u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0628\u0631\u062f\u0633\u062a \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba1 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u0645 \u06c1\u0648 \u06af\u0626\u06cc \u062c\u0628 \u06a9\u06c1 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba 33\u060c000 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u00a0...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safirnews.in\/urdu\/archives\/110885\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T18:05:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1313\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#article\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"headline\":\"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631\",\"datePublished\":\"2026-01-31T18:05:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg\",\"articleSection\":[\"\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/110885#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885\",\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/110885\",\"name\":\"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -\",\"isPartOf\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg\",\"datePublished\":\"2026-01-31T18:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safirnews.in\/urdu\/archives\/110885\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg\",\"width\":850,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safirnews.in\/urdu\/archives\/110885#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safirnews.in\/urdu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safirnews.in\/urdu\/#website\",\"url\":\"https:\/\/safirnews.in\/urdu\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safirnews.in\/urdu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"url\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"contentUrl\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\",\"width\":200,\"height\":82,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png\"},\"sameAs\":[\"https:\/\/safirnews.in\/urdu\"],\"url\":\"https:\/\/safirnews.in\/urdu\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safirnews.in\/urdu\/archives\/110885","og_locale":"en_US","og_type":"article","og_title":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -","og_description":"\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc: \u0645\u06c1\u0646\u06af\u0627\u0626\u06cc \u06a9\u06d2 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u062c\u06c1\u0627\u06ba \u06af\u0632\u0634\u062a\u06c1 \u0686\u0646\u062f \u062f\u0646\u0648\u06ba \u0633\u06d2 \u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0628\u0631\u062f\u0633\u062a \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba1 \u0644\u0627\u06a9\u06be \u0631\u0648\u067e\u06d2 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u0645 \u06c1\u0648 \u06af\u0626\u06cc \u062c\u0628 \u06a9\u06c1 \u0633\u0648\u0646\u06d2 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u06c1\u06cc \u062f\u0646 \u0645\u06cc\u06ba 33\u060c000 \u0641\u06cc 10 \u06af\u0631\u0627\u0645 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06af\u0631\u0627\u0648\u0679 \u0622\u0626\u06cc \u06c1\u06d2\u06d4 \u00a0...","og_url":"https:\/\/safirnews.in\/urdu\/archives\/110885","article_published_time":"2026-01-31T18:05:34+00:00","og_image":[{"width":1313,"height":560,"url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2023\/07\/Logo-Saf-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#article","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885"},"author":{"name":"admin","@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"headline":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631","datePublished":"2026-01-31T18:05:34+00:00","mainEntityOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg","articleSection":["\u0634\u06c1\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safirnews.in\/urdu\/archives\/110885#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safirnews.in\/urdu\/archives\/110885","url":"https:\/\/safirnews.in\/urdu\/archives\/110885","name":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631 -","isPartOf":{"@id":"https:\/\/safirnews.in\/urdu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage"},"image":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage"},"thumbnailUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg","datePublished":"2026-01-31T18:05:34+00:00","breadcrumb":{"@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safirnews.in\/urdu\/archives\/110885"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#primaryimage","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/20260131_231829.jpg","width":850,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/safirnews.in\/urdu\/archives\/110885#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safirnews.in\/urdu"},{"@type":"ListItem","position":2,"name":"\u0633\u0648\u0646\u06d2 \u0627\u0648\u0631 \u0686\u0627\u0646\u062f\u06cc \u06a9\u06cc \u0642\u06cc\u0645\u062a\u06cc\u06ba \u0622\u0633\u0645\u0627\u0646 \u0633\u06d2 \u0632\u0645\u06cc\u0646 \u067e\u0631"}]},{"@type":"WebSite","@id":"https:\/\/safirnews.in\/urdu\/#website","url":"https:\/\/safirnews.in\/urdu\/","name":"","description":"","publisher":{"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safirnews.in\/urdu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/safirnews.in\/urdu\/#\/schema\/person\/36a9843f6cecefee003dec90fdcbed42","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","url":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","contentUrl":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png","width":200,"height":82,"caption":"admin"},"logo":{"@id":"https:\/\/safirnews.in\/urdu\/wp-content\/uploads\/2026\/01\/logo-2.png"},"sameAs":["https:\/\/safirnews.in\/urdu"],"url":"https:\/\/safirnews.in\/urdu\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/110885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/comments?post=110885"}],"version-history":[{"count":0,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/posts\/110885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media\/110882"}],"wp:attachment":[{"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/media?parent=110885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/categories?post=110885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safirnews.in\/urdu\/wp-json\/wp\/v2\/tags?post=110885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}